{"id":17783,"date":"2023-07-06T11:59:58","date_gmt":"2023-07-06T02:59:58","guid":{"rendered":"https:\/\/betifulworld.com\/?p=17783"},"modified":"2023-10-21T14:43:12","modified_gmt":"2023-10-21T05:43:12","slug":"zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii","status":"publish","type":"post","link":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/","title":{"rendered":"Zwiedzanie Koyasan w 2 dni &#8211; Nocleg w Buddyjskiej \u015awi\u0105tyni w Japonii"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17783\" class=\"elementor elementor-17783 elementor-17435\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-760b5b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"760b5b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f3ecc6\" data-id=\"8f3ecc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca98e01 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"ca98e01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Temple-Stay-.jpg\" class=\"attachment-large size-large wp-image-17769\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Temple-Stay-.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Temple-Stay--300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">ZWIEDZANIE KOYASAN W 2 DNI - NOCLEG W BUDDYJSKIEJ \u015aWI\u0104TYNI W JAPONII<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d2c96d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d2c96d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25fb4975\" data-id=\"25fb4975\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-139fdbe elementor-widget elementor-widget-text-editor\" data-id=\"139fdbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Szukasz wyj\u0105tkowych do\u015bwiadcze\u0144 w podr\u00f3\u017cy po Japonii, chcesz dowiedzie\u0107 si\u0119 wi\u0119cej o japo\u0144skiej kulturze i tradycjach buddyjskich lub po prostu pragniesz uciec od zgie\u0142ku wielkiego miasta<\/span><span style=\"font-weight: 400;\">?<\/span><span style=\"font-weight: 400;\"> Dwudniowa wycieczka do Koyasan wraz z noclegiem w buddyjskiej \u015bwi\u0105tyni o ponad 1000-letniej tradycji mo\u017ce by\u0107 tym, czego Ci dok\u0142adnie trzeba.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ce19b34 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ce19b34\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55d1ee4\" data-id=\"55d1ee4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-284cb88e elementor-widget elementor-widget-heading\" data-id=\"284cb88e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Spis tre\u015bci<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a97e2847a6d4\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #108c84;color:#108c84\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #108c84;color:#108c84\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97e2847a6d4\" checked aria-label=\"Prze\u0142\u0105cznik\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#KOYASAN_DLACZEGO_WARTO\" >KOYASAN: DLACZEGO WARTO?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Nocleg_w_buddyjskiej_swiatyni_w_Japonii\" >Nocleg w buddyjskiej \u015bwi\u0105tyni w Japonii<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Koyasan_to_jedno_z_najswietszych_miejsc_w_Japonii\" >Koyasan to jedno z naj\u015bwi\u0119tszych miejsc w Japonii<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#JAK_DOJECHAC_DO_KOYASAN\" >JAK DOJECHA\u0106 DO KOYASAN?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Najblizsze_duze_miasto\" >Najbli\u017csze du\u017ce miasto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Jak_dojechac_z_Osaki_do_Koyasan\" >Jak dojecha\u0107 z Osaki do Koyasan?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Czy_mozna_skorzystac_z_JR_Pass_by_dojechac_do_Koyasan\" >Czy mo\u017cna skorzysta\u0107 z JR Pass, by dojecha\u0107 do Koyasan?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Ile_kosztuje_dojazd_z_Osaki_do_Koyasan\" >Ile kosztuje dojazd z Osaki do Koyasan?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Koyasan_World_Heritage_Ticket_Koyasan_w_2_dni_wygodnie_i_oszczednie\" >Koyasan World Heritage Ticket: Koyasan w 2 dni wygodnie i oszcz\u0119dnie<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#GLOWNE_ATRAKCJE_W_KOYASAN\" >G\u0141\u00d3WNE ATRAKCJE W KOYASAN<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Pobyt_w_buddyjskiej_swiatyni\" >Pobyt w buddyjskiej \u015bwi\u0105tyni<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Cmentarz_Okunoin\" >Cmentarz Okunoin<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Koyasan_najwazniejsze_miejsca_godne_uwagi\" >Koyasan: najwa\u017cniejsze miejsca godne uwagi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Pielgrzymkowy_Szlak_Kobiet_Women_Pilgrims_Course\" >Pielgrzymkowy Szlak Kobiet (Women Pilgrims Course)<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#PLAN_ZWIEDZANIA_KOYASAN_W_2_DNI\" >PLAN ZWIEDZANIA KOYASAN W 2 DNI<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Dzien_1_w_Koyasan\" >Dzie\u0144 1 w Koyasan<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Dzien_2_w_Koyasan\" >Dzie\u0144 2 w Koyasan<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#NOCLEG_W_BUDDYJSKIEJ_SWIATYNI_W_JAPONII_CZEGO_SIE_SPODZIEWAC\" >NOCLEG W BUDDYJSKIEJ \u015aWI\u0104TYNI W JAPONII: CZEGO SI\u0118 SPODZIEWA\u0106?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Pozytywne_strony_pobytu_w_swiatyni_w_Koyasan\" >Pozytywne strony pobytu w \u015bwi\u0105tyni w Koyasan<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Mniej_pozytywne_strony_pobytu_w_swiatyni_Ekoin\" >Mniej pozytywne strony pobytu w \u015bwi\u0105tyni Ekoin<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Recenzje_innych_z_pobytu_w_swiatyni_w_Koyasan\" >Recenzje innych z pobytu w \u015bwi\u0105tyni w Koyasan<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#Nocleg_w_swiatyni_Ekoin_czy_warto\" >Nocleg w \u015bwi\u0105tyni Ekoin: czy warto?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"KOYASAN_DLACZEGO_WARTO\"><\/span>KOYASAN: DLACZEGO WARTO?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10829e59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10829e59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27e0e68b\" data-id=\"27e0e68b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c956d04 elementor-widget elementor-widget-heading\" data-id=\"c956d04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Nocleg_w_buddyjskiej_swiatyni_w_Japonii\"><\/span>Nocleg w buddyjskiej \u015bwi\u0105tyni w Japonii<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55862e45 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55862e45\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b196ba5\" data-id=\"1b196ba5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cf88773 elementor-widget elementor-widget-text-editor\" data-id=\"2cf88773\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Koyasan jest prawdopodobnie najlepszym miejscem na nocleg w \u015bwi\u0105tyni w Japonii. To wyj\u0105tkowe do\u015bwiadczenie, oferowane nie tylko pielgrzymom, ale tak\u017ce zwyk\u0142ym turystom, daj<\/span><span style=\"font-weight: 400;\">\u0105ce<\/span><span style=\"font-weight: 400;\"> wgl\u0105d w \u017cycie mnich\u00f3w i buddyjskie rytua\u0142y. W Koyasan znajduje si\u0119 ponad 50 \u015bwi\u0105ty\u0144 s\u0142u\u017c\u0105cych jako tak zwane kwatery \u015bwi\u0105tynne (<em>temple lodgings\/ shokubo<\/em>), a wiele z nich mo\u017cna zarezerwowa\u0107 za po\u015brednictwem internetowych portali, jak Booking.com lub Agoda, co u\u0142atwia planowanie wycieczki do Koyasan.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60002771 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60002771\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1aee8c\" data-id=\"f1aee8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35f6862c elementor-widget elementor-widget-heading\" data-id=\"35f6862c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Koyasan_to_jedno_z_najswietszych_miejsc_w_Japonii\"><\/span>Koyasan to jedno z naj\u015bwi\u0119tszych miejsc w Japonii<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30a35e40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30a35e40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10b6446\" data-id=\"10b6446\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-501debe5 elementor-widget elementor-widget-text-editor\" data-id=\"501debe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Koyasan <\/span><span style=\"font-weight: 400;\">jest<\/span><span style=\"font-weight: 400;\"> to jedno z najwa\u017cniejszych i naj\u015bwi\u0119tszych miejsc w Japonii. W IX wieku mnich o imieniu Kukai wybra\u0142 odleg\u0142e g\u00f3ry Koyasan na siedzib\u0119 swojego klasztoru i nowej religii, buddyzmu Shingon, kt\u00f3r\u0105 \u201cprzywi\u00f3z\u0142\u201d do Japonii po studiach w Chinach. Kukai, znany po\u015bmiertnie jako Kobo Daishi, do dzi\u015b jest jedn\u0105 z najbardziej czczonych postaci religijnych w Japonii. W Koyasan znajdziesz pi\u0119kne \u015bwi\u0105tynie, mauzoleum Kobo Daishi oraz najwi\u0119kszy i najbardziej spektakularny cmentarz w Japonii \u2013 wszystko otoczone pi\u0119kn\u0105 natur\u0105.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cbc3578 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbc3578\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7a5c0ab\" data-id=\"7a5c0ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00b0a53 elementor-widget elementor-widget-image\" data-id=\"00b0a53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"704\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-sacred-place.jpg\" class=\"attachment-large size-large wp-image-17748\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-sacred-place.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-sacred-place-256x300.jpg 256w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64ba5c8\" data-id=\"64ba5c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a6ddad elementor-widget elementor-widget-heading\" data-id=\"4a6ddad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Witajcie w Koyasan - w jednym z naj\u015bwi\u0119tszych miejsc w Japonii!<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17e4c27 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"17e4c27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa4912e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa4912e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-601c7e2\" data-id=\"601c7e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28a5bf1 elementor-widget elementor-widget-spacer\" data-id=\"28a5bf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bc8f464 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bc8f464\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f14c8ee\" data-id=\"2f14c8ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17ecd7c9 elementor-widget elementor-widget-heading\" data-id=\"17ecd7c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"JAK_DOJECHAC_DO_KOYASAN\"><\/span>JAK DOJECHA\u0106 DO KOYASAN?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ddc4b45 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ddc4b45\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23deebc2\" data-id=\"23deebc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43e8bcc3 elementor-widget elementor-widget-heading\" data-id=\"43e8bcc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Najblizsze_duze_miasto\"><\/span>Najbli\u017csze du\u017ce miasto<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47040e91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47040e91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-679c6eef\" data-id=\"679c6eef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6ab9ba elementor-widget elementor-widget-text-editor\" data-id=\"d6ab9ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Najbli\u017cszym du\u017cym miastem w okolicy Koyasan jest Osaka. Chocia\u017c na pocz\u0105tku mo\u017ce si\u0119 to wydawa\u0107 skomplikowane, poniewa\u017c nale\u017cy skorzysta\u0107 z poci\u0105gu, kolejki linowej i autobusu, by dotrze\u0107 do \u015bwi\u0105ty\u0144 w Koyasan, podr\u00f3\u017c z Osaki (stacja Namba) do Koyasan jest bardzo wygodna i zajmuje dwie godziny. Ze wzgl\u0119du na nieustannie zmieniaj\u0105ce si\u0119 za oknem pi\u0119kne krajobrazy wiejsko-g\u00f3rskie, wspominam t\u0119 podr\u00f3\u017c bardzo dobrze. To niesamowite, \u017ce w zaledwie dwie godziny mo\u017cna uciec z g\u0119stej betonowej d\u017cungli Osaki do \u015bwi\u0119tych zielonych g\u00f3r Koyasan.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7572ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7572ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e237a31\" data-id=\"e237a31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71e490b elementor-widget elementor-widget-image\" data-id=\"71e490b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"745\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Osaka-betifulworld.jpg\" class=\"attachment-large size-large wp-image-17589\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Osaka-betifulworld.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Osaka-betifulworld-242x300.jpg 242w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3330464\" data-id=\"3330464\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcdf88b elementor-widget elementor-widget-heading\" data-id=\"bcdf88b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">dwa r\u00f3\u017cne \u015bwiaty w zaledwie dwie godziny<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-673c63d elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"673c63d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-99ccbb3\" data-id=\"99ccbb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff552a5 elementor-widget elementor-widget-image\" data-id=\"ff552a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"745\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-forests.jpg\" class=\"attachment-large size-large wp-image-17591\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-forests.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-forests-242x300.jpg 242w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0215530 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0215530\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69b65f1\" data-id=\"69b65f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b075a7 elementor-widget elementor-widget-spacer\" data-id=\"3b075a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a66af08 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a66af08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50b3de6e\" data-id=\"50b3de6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32156657 elementor-widget elementor-widget-heading\" data-id=\"32156657\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Jak_dojechac_z_Osaki_do_Koyasan\"><\/span>Jak dojecha\u0107 z Osaki do Koyasan?<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-217b2d3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"217b2d3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d877974\" data-id=\"2d877974\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e058772 elementor-widget elementor-widget-text-editor\" data-id=\"7e058772\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Do Koyasan dojedziecie poci\u0105giem linii Nankai Koya ze stacji Namba w Osace. Najszybsz\u0105 opcj\u0105 jest Limited Express, kt\u00f3ry dojedzie do Koyasan w 80 minut. Ewentualnie mo\u017cna skorzysta\u0107 ze zwyk\u0142ego poci\u0105gu ekspresowego z kr\u00f3tk\u0105 przesiadk\u0105 na stacji Hashimoto (czas przejazdu to oko\u0142o 105 minut). Ja jecha\u0142am w\u0142a\u015bnie takim wolniejszym poci\u0105giem i nie mog\u0119 na nic narzeka\u0107. Przesiadka w Hashimoto jest bardzo \u0142atwa, poniewa\u017c nie trzeba nawet zmienia\u0107 peronu, a poci\u0105gi s\u0105 skoordynowane na czas. No przecie\u017c to w ko\u0144cu Japonia! \ud83d\ude42<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35e0b17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35e0b17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c4ded3\" data-id=\"7c4ded3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6c7b61 elementor-widget elementor-widget-heading\" data-id=\"a6c7b61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Przesiadka w Hashimoto jest bajecznie prosta<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0955b1a elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"0955b1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d3d89d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d3d89d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e1595b\" data-id=\"5e1595b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7544054 elementor-widget elementor-widget-image\" data-id=\"7544054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"699\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Train-to-Koyasan.jpg\" class=\"attachment-large size-large wp-image-17596\" alt=\"Train to Koyasan\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Train-to-Koyasan.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Train-to-Koyasan-258x300.jpg 258w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e8e4498\" data-id=\"e8e4498\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15283f1 elementor-widget elementor-widget-image\" data-id=\"15283f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"701\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Travel-to-Koyasan-Hashimoto-transfer.jpg\" class=\"attachment-large size-large wp-image-17594\" alt=\"Travel to Koyasan - Hashimoto transfer\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Travel-to-Koyasan-Hashimoto-transfer.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Travel-to-Koyasan-Hashimoto-transfer-257x300.jpg 257w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-debe4cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"debe4cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0dd8b7\" data-id=\"b0dd8b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0010d06 elementor-widget elementor-widget-spacer\" data-id=\"0010d06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf00b02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf00b02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-801d47e\" data-id=\"801d47e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6d1656 elementor-widget elementor-widget-text-editor\" data-id=\"f6d1656\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Po dotarciu do ostatniego przystanku, stacji Gokurakubashi, nale\u017cy przesi\u0105\u015b\u0107 si\u0119 do kolejki linowej. Podr\u00f3\u017c do Koyasan trwa oko\u0142o 5 minut.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2832a95e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2832a95e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60cd89bf\" data-id=\"60cd89bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-156e14f elementor-widget elementor-widget-heading\" data-id=\"156e14f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Czy_mozna_skorzystac_z_JR_Pass_by_dojechac_do_Koyasan\"><\/span>Czy mo\u017cna skorzysta\u0107 z JR Pass, by dojecha\u0107 do Koyasan?<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-588a873d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"588a873d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-213e41f5\" data-id=\"213e41f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b1f78b8 elementor-widget elementor-widget-text-editor\" data-id=\"2b1f78b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nie, Japan Rail Pass (JR Pass) nie obejmuje przejazd\u00f3w liniami Nankai Koya do Koyasan.\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26d59b1b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26d59b1b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32379bba\" data-id=\"32379bba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70d63854 elementor-widget elementor-widget-heading\" data-id=\"70d63854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Ile_kosztuje_dojazd_z_Osaki_do_Koyasan\"><\/span>Ile kosztuje dojazd z Osaki do Koyasan? <span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64a34be6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64a34be6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a78223b\" data-id=\"1a78223b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-783788d5 elementor-widget elementor-widget-text-editor\" data-id=\"783788d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Bilet w jedn\u0105 stron\u0119 (poci\u0105g + kolejka linowa) z Osaki do Koyasan kosztuje oko\u0142o 1400 JPY (zwyk\u0142y ekspres) i oko\u0142o 2200 JPY (Limited Express).<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19fc55bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19fc55bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54a3c600\" data-id=\"54a3c600\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c7f349c elementor-widget elementor-widget-heading\" data-id=\"6c7f349c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Koyasan_World_Heritage_Ticket_Koyasan_w_2_dni_wygodnie_i_oszczednie\"><\/span>Koyasan World Heritage Ticket: Koyasan w 2 dni wygodnie i oszcz\u0119dnie<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cd14297 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cd14297\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c8149dc\" data-id=\"1c8149dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-619379b3 elementor-widget elementor-widget-text-editor\" data-id=\"619379b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Bilet <\/span><i><span style=\"font-weight: 400;\">Koyasan World Heritage Ticket <\/span><\/i><span style=\"font-weight: 400;\">(3080 JPY) to \u015bwietny spos\u00f3b na oszcz\u0119dno\u015b\u0107 podczas wycieczki do Koyasan. Obejmuje on bilet w obie strony z Osaki do Koyasan (zwyk\u0142ym ekspresem), nieograniczone przejazdy autobusem po Koyasan oraz zni\u017ck\u0119 na wst\u0119p do g\u0142\u00f3wnych atrakcji. Bilet jest wa\u017cny przez dwa kolejne dni i jest dost\u0119pny na stacjach kolei Nankai w Osace: Namba, Shin-Imamiya i Tengachaya.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nawet je\u015bli podr\u00f3\u017cujesz tylko z Namby do g\u0142\u00f3wnej atrakcji Koyasan &#8211; Okunoin, pomo\u017ce on zaoszcz\u0119dzi\u0107, poniewa\u017c bilet w jedn\u0105 stron\u0119 kosztuje ponad 1800 JPY (1390 JPY za poci\u0105g i kolejk\u0119 linow\u0105 + 420 JPY za autobus z Koyasan do Okunoin).\u00a0 A je\u015bli planujesz zwiedzanie Koyasan w 2 dni, tak jak my, zaoszcz\u0119dzisz du\u017co wi\u0119cej.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Je\u015bli <\/span><span style=\"font-weight: 400;\">za\u015b<\/span><span style=\"font-weight: 400;\"> planujesz podr\u00f3\u017c do Koyasan poci\u0105giem Limited Express, po prostu kup dro\u017csz\u0105 wersj\u0119 biletu <\/span><i><span style=\"font-weight: 400;\">Koyasan World Heritage Ticket<\/span><\/i><span style=\"font-weight: 400;\"> (3630 JPY).<\/span><\/p>\n<p><strong><a href=\"https:\/\/www.nankaikoya.jp\/en\/stations\/ticket.html\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Wi\u0119cej na temat Koyasan World Heritage Ticket<\/span> <\/a><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Je\u015bli natomiast nie zdecydujesz si\u0119 na kupno <\/span><i><span style=\"font-weight: 400;\">Koyasan World Heritage Ticket, <\/span><\/i><span style=\"font-weight: 400;\">mo\u017cesz u\u017cy\u0107 karty Pasmo\/Suica by zap\u0142aci\u0107 za przejazd poci\u0105giem, kolejk\u0105 linow\u0105 i autobusem w obr\u0119bie Mount Koya. Pami\u0119taj tylko, \u017ce jak zwykle w Japonii, podr\u00f3\u017cuj\u0105c poci\u0105giem Limited Express, musisz ui\u015bci\u0107 dodatkow\u0105 op\u0142at\u0119.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ada3fb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ada3fb5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23f5d470\" data-id=\"23f5d470\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-367b58a0 elementor-widget elementor-widget-heading\" data-id=\"367b58a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"GLOWNE_ATRAKCJE_W_KOYASAN\"><\/span>G\u0141\u00d3WNE ATRAKCJE W KOYASAN<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63443c23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63443c23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d70a4d6\" data-id=\"6d70a4d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ba34d67 elementor-widget elementor-widget-heading\" data-id=\"4ba34d67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Pobyt_w_buddyjskiej_swiatyni\"><\/span>Pobyt w buddyjskiej \u015bwi\u0105tyni <span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c3a3051 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c3a3051\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74eff38a\" data-id=\"74eff38a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-306407d4 elementor-widget elementor-widget-text-editor\" data-id=\"306407d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pobyt w \u015bwi\u0105tyni o 1200-letniej historii i mo\u017cliwo\u015b\u0107 uczestniczenia w codziennych rytua\u0142ach mnich\u00f3w czyni Koyasan naprawd\u0119 wyj\u0105tkowym. Nocleg w \u015bwi\u0105tyni oznacza r\u00f3wnie\u017c pobyt w tradycyjnie urz\u0105dzonym japo\u0144skim pokoju z mat\u0105 tatami i zar\u00f3wno wyszukane, jak i pi\u0119knie podane buddyjskie posi\u0142ki, \u015bwietne dla zdrowia &#8211; cia\u0142a i ducha.<\/p>\n<p>Najwa\u017cniejsze atrakcje Koyasan mo\u017cna teoretycznie zobaczy\u0107 podczas jednodniowej wycieczki z Osaki, ale noc w \u015bwi\u0105tyni w Koyasan jest powodem, dla kt\u00f3rego wi\u0119kszo\u015b\u0107 ludzi decyduje si\u0119 tu przyjecha\u0107. Wi\u0119cej o tym, czego si\u0119 spodziewa\u0107 i moje wra\u017cenia z pobytu w \u015bwi\u0105tyni Eko-in w dalszej cz\u0119\u015bci artyku\u0142u.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c37a6fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c37a6fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-200772a\" data-id=\"200772a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4522914 elementor-widget elementor-widget-heading\" data-id=\"4522914\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Buddyjska kolacja, a uczta w \u015bwi\u0105tyni <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b494bd elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"8b494bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dbf9122\" data-id=\"dbf9122\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13cdc08 elementor-widget elementor-widget-image\" data-id=\"13cdc08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-dinner-served-in-the-room-e1687321097923.jpg\" class=\"attachment-large size-large wp-image-17557\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84087a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84087a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7b038a\" data-id=\"f7b038a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6c14a0 elementor-widget elementor-widget-spacer\" data-id=\"e6c14a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35620e3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35620e3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1876b5a4\" data-id=\"1876b5a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-190c0969 elementor-widget elementor-widget-heading\" data-id=\"190c0969\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Cmentarz_Okunoin\"><\/span>Cmentarz Okunoin<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d4641b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d4641b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b48c7ae\" data-id=\"b48c7ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e494a8d elementor-widget elementor-widget-text-editor\" data-id=\"e494a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Okunoin, najwi\u0119kszy cmentarz w Japonii, mieszcz\u0105cy ponad 200 tysi\u0119cy nagrobk\u00f3w wzd\u0142u\u017c 2-kilometrowego podej\u015bcia do mauzoleum Kobo Daishi, jest jednym z naj\u015bwi\u0119tszych miejsc w Japonii.<\/p>\n<p>Co ciekawe, uwa\u017ca si\u0119, \u017ce Kobo Daishi odpoczywa w wiecznej medytacji. Czekaj\u0105c na Przysz\u0142ego Budd\u0119, zapewnia ulg\u0119 tym, kt\u00f3rzy w mi\u0119dzyczasie prosz\u0105 o zbawienie. Dlatego te\u017c w nadziei na szybkie zbawienie dzi\u0119ki blisko\u015bci Kobo Daishi cmentarz jest tak ogromny! Wiele os\u00f3b zosta\u0142o pochowanych tu na przestrzeni wiek\u00f3w, a liczni pielgrzymi odwiedzaj\u0105 Koyasan ka\u017cdego roku.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f12167a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f12167a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c93f4e6\" data-id=\"c93f4e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6493b2b elementor-widget elementor-widget-image\" data-id=\"6493b2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-pilgrim.jpg\" class=\"attachment-large size-large wp-image-17694\" alt=\"Okunoin Cementary Koyasan pilgrim\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-pilgrim.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-pilgrim-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0f24834\" data-id=\"0f24834\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9e4b34 elementor-widget elementor-widget-image\" data-id=\"c9e4b34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-torii.jpg\" class=\"attachment-large size-large wp-image-17702\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-torii.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-torii-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e331c98\" data-id=\"e331c98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8940551 elementor-widget elementor-widget-image\" data-id=\"8940551\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-moss-Koyasan-.jpg\" class=\"attachment-large size-large wp-image-17716\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-moss-Koyasan-.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-moss-Koyasan--225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-504c0273 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"504c0273\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-443a68ca\" data-id=\"443a68ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88d9804 elementor-widget elementor-widget-text-editor\" data-id=\"88d9804\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Torodo Hall to g\u0142\u00f3wny budynek Okunoin z tysi\u0105cami latar\u0144 podarowanych przez wiernych, kt\u00f3re pal\u0105 si\u0119 wiecznie. W\u0142a\u015bnie za Torodo Hall znajduje si\u0119 mauzoleum Kobo Daishi, czyli miejsce jego wiecznej medytacji. <span style=\"font-weight: 400;\">Za mostem Gobyobashi<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> prowadz\u0105cym do Torodo Hall i mauzoleum<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> zabronione jest fotografowanie, jedzenie i picie.<\/span><\/p>\n<p>Zw\u0142aszcza noc\u0105 zwiedzanie cmentarza Okunoin stanowi niezapomniane prze\u017cycie. Atmosfera jest naprawd\u0119 mistyczna. \u015acie\u017cka jest \u0142adnie o\u015bwietlona i mo\u017cna doj\u015b\u0107 pieszo a\u017c do mauzoleum. Widok tysi\u0119cy lampion\u00f3w noc\u0105 robi szczeg\u00f3lne wra\u017cenie.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fe3bae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fe3bae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1a75a5\" data-id=\"f1a75a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dab2314 elementor-widget elementor-widget-heading\" data-id=\"dab2314\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">WSKAZ\u00d3WKA #1 ZWIEDZANIE CMENTARZA OKUNOIN<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c6c7e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c6c7e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d176828\" data-id=\"d176828\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37ac66e elementor-widget elementor-widget-text-editor\" data-id=\"37ac66e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Poniewa\u017c w nocy Torodo Hall jest zamkni\u0119ty i nie wszystkie osobliwo\u015bci i figurki na cmentarzu mo\u017cna dobrze widzie\u0107, to gor\u0105co polecam dwukrotne odwiedzenie Okunoin (wieczorem i rankiem). Nawet je\u015bli zostajesz w Koyasan tylko na jedn\u0105 noc, uwierz mi, \u017ce warto.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8c639b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8c639b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0f333fb\" data-id=\"0f333fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f23bde4 elementor-widget elementor-widget-image\" data-id=\"f23bde4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-2-day-itinerary.jpg\" class=\"attachment-large size-large wp-image-17700\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-2-day-itinerary.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-2-day-itinerary-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a0e029c\" data-id=\"a0e029c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d893fef elementor-widget elementor-widget-image\" data-id=\"d893fef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Panasonic.jpg\" class=\"attachment-large size-large wp-image-17750\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Panasonic.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Panasonic-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc647bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc647bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-91561c2\" data-id=\"91561c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1de7b7e elementor-widget elementor-widget-spacer\" data-id=\"1de7b7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f6d7de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f6d7de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d960f98\" data-id=\"d960f98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9197450 elementor-widget elementor-widget-heading\" data-id=\"9197450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">WSKAZ\u00d3WKA #2 OKUNOIN WALKING TOUR<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-557bb09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"557bb09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc75607\" data-id=\"cc75607\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-416e90b elementor-widget elementor-widget-text-editor\" data-id=\"416e90b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Je\u015bli nocna wizyta na cmentarzu wydaje si\u0119 nieco przera\u017caj\u0105ca i przyda\u0142oby Ci si\u0119 towarzystwo, nie martw si\u0119, mam dla Ciebie idealne rozwi\u0105zanie. Zapisz si\u0119 na nocn\u0105 wycieczk\u0119 po Okunoin organizowan\u0105 (odp\u0142atnie) w \u015bwi\u0105tyni Ekoin. My mieli\u015bmy nawet do\u0142\u0105czy\u0107 do takiej wycieczki, ale niestety (albo stety) z powodu deszczu zosta\u0142a odwo\u0142ana, wi\u0119c kiedy przesta\u0142o pada\u0107, sami zwiedzali\u015bmy cmentarz i\u2026<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60cb9b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60cb9b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0e6b14a\" data-id=\"0e6b14a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6951020 elementor-widget elementor-widget-image\" data-id=\"6951020\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"673\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-at-night-Koyasan-2-days.jpg\" class=\"attachment-large size-large wp-image-17657\" alt=\"Okunoin Cementary at night - Koyasan 2 days\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-at-night-Koyasan-2-days.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-at-night-Koyasan-2-days-267x300.jpg 267w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4880b45\" data-id=\"4880b45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f7b717 elementor-widget elementor-widget-heading\" data-id=\"9f7b717\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">...wcale nie by\u0142o tak strasznie... \ud83d\ude09<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed9b787 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"ed9b787\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b8be14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b8be14\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6235632\" data-id=\"6235632\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2ffdca elementor-widget elementor-widget-spacer\" data-id=\"f2ffdca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5be40d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5be40d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e5e8f9\" data-id=\"6e5e8f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05e6030 elementor-widget elementor-widget-heading\" data-id=\"05e6030\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Koyasan_najwazniejsze_miejsca_godne_uwagi\"><\/span>Koyasan: najwa\u017cniejsze miejsca godne uwagi<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b5391c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b5391c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37ffb235\" data-id=\"37ffb235\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e8f9520 elementor-widget elementor-widget-heading\" data-id=\"3e8f9520\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Kompleks \u015bwi\u0105tynny Danjo Garan<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39d7021b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39d7021b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fcdd6c9\" data-id=\"2fcdd6c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25dea56a elementor-widget elementor-widget-text-editor\" data-id=\"25dea56a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Drugi naj\u015bwi\u0119tszy punkt w Koyasan to pierwsze miejsce, w kt\u00f3rym Kobo-Daishi zbudowa\u0142 \u015bwi\u0105tyni\u0119. Wed\u0142ug legendy Kukai na kr\u00f3tko przed wyjazdem z Chin do Japonii, po studiach buddyzmu ezoterycznego, rzuci\u0142 swoj\u0105 wad\u017cr\u0119 \u2013 narz\u0119dzie u\u017cywane do rytua\u0142\u00f3w \u2013 w kierunku Archipelagu Japo\u0144skiego, aby odkry\u0107 najlepsze miejsce do propagowania buddyzmu. Poniewa\u017c wad\u017cra spad\u0142a na sosn\u0119 (kt\u00f3ra wci\u0105\u017c tu ro\u015bnie), zbudowa\u0142 w\u0142a\u015bnie w Koyasan swoj\u0105 \u015bwi\u0105tyni\u0119.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8352a81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8352a81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c2c5f7\" data-id=\"4c2c5f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb13ee0 elementor-widget elementor-widget-heading\" data-id=\"cb13ee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Zarezerwuj troch\u0119 czasu na zwiedzanie kompleksu Danjo Garan, bo w cedrowym lesie ukrytych jest wiele skarb\u00f3w!<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba095e7 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"ba095e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3c2a79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3c2a79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a4392d1\" data-id=\"a4392d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-495dc17 elementor-widget elementor-widget-image\" data-id=\"495dc17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-Danjo-Garan-Temple-Complex.jpg\" class=\"attachment-large size-large wp-image-17630\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-Danjo-Garan-Temple-Complex.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-Danjo-Garan-Temple-Complex-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d7bae0a\" data-id=\"d7bae0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8f6795 elementor-widget elementor-widget-image\" data-id=\"a8f6795\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"801\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-itinerary-Danjo-Garan-Temple-Complex.jpg\" class=\"attachment-large size-large wp-image-17628\" alt=\"Koyasan itinerary - Danjo Garan Temple Complex\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-itinerary-Danjo-Garan-Temple-Complex.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-itinerary-Danjo-Garan-Temple-Complex-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ca66dc\" data-id=\"7ca66dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad44c2e elementor-widget elementor-widget-image\" data-id=\"ad44c2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-torii-gate.jpg\" class=\"attachment-large size-large wp-image-17624\" alt=\"Danjo Garan Temple Complex torii gate\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-torii-gate.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-torii-gate-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e07a44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e07a44\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22de1da\" data-id=\"22de1da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5a08ae elementor-widget elementor-widget-text-editor\" data-id=\"b5a08ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>W kompleksie znajduje si\u0119 \u0142\u0105cznie 19 budynk\u00f3w. Najbardziej imponuj\u0105ca pagoda Konpon-Daito i hala Kon-Do by\u0142y wielokrotnie niszczone przez po\u017cary i zosta\u0142y odbudowane w XX wieku. Obie wymagaj\u0105 op\u0142aty za wst\u0119p w wysoko\u015bci 500 JPY (20% zni\u017cki z biletem<em> Koyasan World Heritage Ticket<\/em>).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ecaa939 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ecaa939\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-293354cc\" data-id=\"293354cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b17fdc elementor-widget elementor-widget-heading\" data-id=\"0b17fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">WSKAZ\u00d3WKA #3 ZWIEDZANIE KOMPLEKSU DANJO GARAN <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19b4302a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19b4302a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fc77bed\" data-id=\"1fc77bed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f849e1f elementor-widget elementor-widget-text-editor\" data-id=\"7f849e1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Je\u015bli planujecie wej\u015bcie tylko do jednego z budynk\u00f3w &#8211; polecam wysok\u0105 na 45 metr\u00f3w czerwon\u0105 pagod\u0119 Konpon Daito. Zawiera rzadk\u0105 mandal\u0119 3D (mandale to zazwyczaj obrazy 2D<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> przedstawiaj\u0105ce duchow\u0105 podr\u00f3\u017c \/ wszech\u015bwiat) z centralnym pos\u0105giem Kosmicznego Buddy<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> otoczonym pos\u0105gami i malowid\u0142ami na filarach, co jest bardzo wyj\u0105tkowe.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0143c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0143c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0419df7\" data-id=\"0419df7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-944bdbc elementor-widget elementor-widget-image\" data-id=\"944bdbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"514\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-day-itinerary-Danjo-Garan-Temple-Complex.jpg\" class=\"attachment-large size-large wp-image-17620\" alt=\"Koyasan 2 day itinerary - Danjo Garan Temple Complex\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-day-itinerary-Danjo-Garan-Temple-Complex.jpg 1000w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-day-itinerary-Danjo-Garan-Temple-Complex-300x154.jpg 300w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-day-itinerary-Danjo-Garan-Temple-Complex-768x395.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Danjo Garan Temple Complex<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd855d0 elementor-widget elementor-widget-spacer\" data-id=\"dd855d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9addf4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9addf4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-628569a0\" data-id=\"628569a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6342c417 elementor-widget elementor-widget-heading\" data-id=\"6342c417\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u015awi\u0105tynia Kongobuji<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-214a72ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"214a72ec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25869124\" data-id=\"25869124\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-392c9d9c elementor-widget elementor-widget-text-editor\" data-id=\"392c9d9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jest to siedziba sprowadzonego do Japonii przez Kobo Daishi buddyzmu Shingon (4000 \u015bwi\u0105ty\u0144 na ca\u0142ym \u015bwiecie), ze wspania\u0142ym ogrodem skalnym (najwi\u0119kszym w Japonii) i pi\u0119knymi obrazami znanych artyst\u00f3w na imponuj\u0105cych przesuwanych drzwiach (<em>fusuma<\/em>). \u015awi\u0105tynia znana jest r\u00f3wnie\u017c z pomieszczenia, w kt\u00f3rym jeden ze s\u0142ynnych japo\u0144skich wojownik\u00f3w &#8211; Toyotomi Hidetsugu &#8211; zosta\u0142 zmuszony do pope\u0142nienia samob\u00f3jstwa.<\/p>\n<p>Nie wiedzieli\u015bmy, czy wej\u015b\u0107 czy nie, poniewa\u017c op\u0142ata za wst\u0119p jest do\u015b\u0107 wysoka &#8211; 1000 JPY, ale cieszymy si\u0119, \u017ce to zrobili\u015bmy. \u015awi\u0105tynia Kongobuji jest naprawd\u0119 ciekawa, a z biletem <em>Koyasan World Heritage Ticket<\/em> masz 20% zni\u017cki.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb08eb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb08eb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0eb59c5\" data-id=\"0eb59c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4aa6f54 elementor-widget elementor-widget-image\" data-id=\"4aa6f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"699\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Kongobuji-Temple-Koyasan.jpg\" class=\"attachment-large size-large wp-image-17652\" alt=\"Kongobuji Temple - Koyasan\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Kongobuji-Temple-Koyasan.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Kongobuji-Temple-Koyasan-258x300.jpg 258w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d6da15c\" data-id=\"d6da15c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39fcf5f elementor-widget elementor-widget-image\" data-id=\"39fcf5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"698\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Kongobuji-Temple-Koyasan-in-2-days.jpg\" class=\"attachment-large size-large wp-image-17648\" alt=\"Kongobuji Temple - Koyasan in 2 days\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Kongobuji-Temple-Koyasan-in-2-days.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Kongobuji-Temple-Koyasan-in-2-days-258x300.jpg 258w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30d3605 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30d3605\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3d4126\" data-id=\"e3d4126\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d18e803 elementor-widget elementor-widget-spacer\" data-id=\"d18e803\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-714ec871 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"714ec871\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26acbaaa\" data-id=\"26acbaaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62c09811 elementor-widget elementor-widget-heading\" data-id=\"62c09811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Brama Daimona (Daimon Gate)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6f2f26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6f2f26\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac4b290\" data-id=\"ac4b290\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-770357b elementor-widget elementor-widget-text-editor\" data-id=\"770357b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wysoka na 25 metr\u00f3w majestatyczna brama, przebudowana w 1705 roku, z dwoma stra\u017cnikami na \u015bcie\u017cce. G\u0142\u00f3wna zachodnia brama wjazdowa do Koyasan, kt\u00f3r\u0105 naprawd\u0119 warto zobaczy\u0107.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7276baa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7276baa6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4dd38f3d\" data-id=\"4dd38f3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8a50f8 elementor-widget elementor-widget-image\" data-id=\"e8a50f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"997\" height=\"715\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Daimon-Gate.jpg\" class=\"attachment-large size-large wp-image-17601\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Daimon-Gate.jpg 997w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Daimon-Gate-300x215.jpg 300w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Daimon-Gate-768x551.jpg 768w\" sizes=\"(max-width: 997px) 100vw, 997px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c90c71b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c90c71b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10459443\" data-id=\"10459443\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15dbf637 elementor-widget elementor-widget-heading\" data-id=\"15dbf637\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Pielgrzymkowy_Szlak_Kobiet_Women_Pilgrims_Course\"><\/span>Pielgrzymkowy Szlak Kobiet (Women Pilgrims Course) <span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76d33fbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76d33fbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48cc67cf\" data-id=\"48cc67cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a0a17da elementor-widget elementor-widget-text-editor\" data-id=\"7a0a17da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nie by\u0142abym sob\u0105, gdybym nie wcisn\u0119\u0142a ma\u0142ej g\u00f3rskiej w\u0119dr\u00f3wki w 2-dniowy plan zwiedzania Koyasan \ud83d\ude42<\/p>\n<p>Przed 1872 rokiem kobiety mia\u0142y zakaz wst\u0119pu do wielu \u015bwi\u0119tych miejsc w Japonii, w tym do Koyasan i na g\u00f3r\u0119 Fuji. Te najbardziej zdeterminowane wyznawczynie, pragn\u0105ce z\u0142o\u017cy\u0107 ho\u0142d mauzoleum Kobo-Daishi, do kt\u00f3rego nie mog\u0142y si\u0119 zbli\u017cy\u0107, udepta\u0142y otaczaj\u0105cy \u015bwi\u0119ty obszar Women Pilgrims Course. 7-kilometrowy szlak dla kobiet pielgrzym\u00f3w biegnie wok\u00f3\u0142 Koyasan z Nyonindo Hall przez Benten Peak, Daimon Gate i ko\u0144czy si\u0119 przy wej\u015bciu do Okunoin.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff6a8b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff6a8b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a7d5e8\" data-id=\"2a7d5e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34d3cfc elementor-widget elementor-widget-image\" data-id=\"34d3cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"730\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-2-day-itinerary.jpg\" class=\"attachment-large size-large wp-image-17665\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-2-day-itinerary.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-2-day-itinerary-247x300.jpg 247w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2bd1d26\" data-id=\"2bd1d26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-647a9cf elementor-widget elementor-widget-image\" data-id=\"647a9cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"731\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-hiking.jpg\" class=\"attachment-large size-large wp-image-17667\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-hiking.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-hiking-246x300.jpg 246w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab68c09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab68c09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5302433\" data-id=\"5302433\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3c78b4 elementor-widget elementor-widget-text-editor\" data-id=\"d3c78b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Je\u015bli nie macie zbyt wiele czasu, a nadal chcecie si\u0119 nacieszy\u0107 pi\u0119knymi lasami Koyasan tak jak my, mo\u017cecie przej\u015b\u0107 jedynie cz\u0119\u015b\u0107 trasy. 2-kilometrowa trasa z Nyonindo Hall przez Benten Peak do Daimon Gate prowadzi \u0142agodnie pod g\u00f3r\u0119 przez g\u0119sty las i kilka malowniczych czerwonych bram torii i jest bardzo przyjemna. Trasa zaj\u0119\u0142a nam oko\u0142o godziny (z du\u017c\u0105 liczb\u0105 przerw na tzw. le\u015bn\u0105 k\u0105piel).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74d4ee7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74d4ee7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f39cf1\" data-id=\"9f39cf1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5b3909 elementor-widget elementor-widget-image\" data-id=\"d5b3909\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"886\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-map.jpg\" class=\"attachment-large size-large wp-image-17669\" alt=\"Women Pilgrims Course Koyasan -map\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-map.jpg 1000w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-map-300x266.jpg 300w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Women-Pilgrims-Course-Koyasan-map-768x680.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Mapa na trasie Women Pilgrims Course. Szlak Pielgrzymkowy Kobiet oznaczony jest kolorem fioletowym. Nasza 2-kilometrowa trasa rozpocz\u0119\u0142a si\u0119 w Nyonindo Hall (1) i zako\u0144czy\u0142a si\u0119 w Daimon Gate (5).<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bc28a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bc28a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-003a809\" data-id=\"003a809\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb8d111 elementor-widget elementor-widget-spacer\" data-id=\"bb8d111\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30776189 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30776189\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-58de48f7\" data-id=\"58de48f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23b52f8c elementor-widget elementor-widget-heading\" data-id=\"23b52f8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"PLAN_ZWIEDZANIA_KOYASAN_W_2_DNI\"><\/span>PLAN ZWIEDZANIA KOYASAN W 2 DNI<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35750a7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35750a7d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c7d4468\" data-id=\"1c7d4468\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a2ac355 elementor-widget elementor-widget-text-editor\" data-id=\"3a2ac355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">M\u00f3j 2-dniowy plan podr\u00f3\u017cy do Koyasan to tak naprawd\u0119 24-godzinny pobyt. Oto szczeg\u00f3\u0142y<\/span><span style=\"font-weight: 400;\">\u2026<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49bb581a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49bb581a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11140821\" data-id=\"11140821\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26083a89 elementor-widget elementor-widget-heading\" data-id=\"26083a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Dzien_1_w_Koyasan\"><\/span>Dzie\u0144 1 w Koyasan<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-643b966 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"643b966\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a66fdc\" data-id=\"1a66fdc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b92286d elementor-widget elementor-widget-heading\" data-id=\"b92286d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">PRZYJAZD DO KOYASAN<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74fb65e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74fb65e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31bfff6\" data-id=\"31bfff6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7d4749 elementor-widget elementor-widget-text-editor\" data-id=\"e7d4749\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Je\u015bli wsi\u0105dziecie do Limited Express o 14:00 z Namby, to dotrzecie do \u015bwi\u0105tyni Ekoin o 16:00\u00a0 i b\u0119dziecie mieli szans\u0119 wzi\u0105\u0107 udzia\u0142 w bezp\u0142atnej medytacji o 16:30.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86d2ea2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86d2ea2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b18f38f\" data-id=\"b18f38f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54c51d3 elementor-widget elementor-widget-heading\" data-id=\"54c51d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">W Koyasan przywita\u0142a nas mg\u0142a<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f105d5 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"4f105d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-661b5f7\" data-id=\"661b5f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03cf94f elementor-widget elementor-widget-image\" data-id=\"03cf94f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"572\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-Station.jpg\" class=\"attachment-large size-large wp-image-17722\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-Station.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-Station-300x286.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb07f46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb07f46\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-760b104\" data-id=\"760b104\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e20e39 elementor-widget elementor-widget-heading\" data-id=\"9e20e39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">KOLACJA O 17:30<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3637c71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3637c71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90baaeb\" data-id=\"90baaeb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ebf34d elementor-widget elementor-widget-text-editor\" data-id=\"2ebf34d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Buddyjskie posi\u0142ki serwowane w \u015bwi\u0105tyni (<em>shojin ryori<\/em>) s\u0105 smaczne, pi\u0119knie podane i po\u017cywne zar\u00f3wno dla cia\u0142a, jak i umys\u0142u. Ciesz si\u0119 atmosfer\u0105 tradycyjnego japo\u0144skiego wystroju podczas kolacji<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> podanej przez mnicha do <\/span><span style=\"font-weight: 400;\">T<\/span><span style=\"font-weight: 400;\">wojego pokoju.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-865f2fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"865f2fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-278c96c\" data-id=\"278c96c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a95ea3 elementor-widget elementor-widget-heading\" data-id=\"6a95ea3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">WIECZ\u00d3R<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-700a4d82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"700a4d82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2187b103\" data-id=\"2187b103\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2be23648 elementor-widget elementor-widget-text-editor\" data-id=\"2be23648\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Po kolacji udaj si\u0119 do najbardziej klimatycznego miejsca w Koyasan &#8211; Okunoin, znajduj\u0105cego si\u0119 przed \u015bwi\u0105tyni\u0105 Ekoin. Nocny spacer po wielowiekowym cmentarzu, otoczonym wysokimi cedrami i niezliczonymi nagrobkami, stanowi\u0107 b\u0119dzie niezapomniane prze\u017cycie. Jak ju\u017c wcze\u015bniej wspomnia\u0142am, macie dwie mo\u017cliwo\u015bci: mo\u017cecie zwiedza\u0107 cmentarz samemu lub do\u0142\u0105czy\u0107 do wycieczki organizowanej przez \u015bwi\u0105tyni\u0119 Ekoin.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a9a44f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a9a44f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-333a814\" data-id=\"333a814\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1983338 elementor-widget elementor-widget-image\" data-id=\"1983338\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"574\" height=\"568\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-temple-at-night.jpg\" class=\"attachment-large size-large wp-image-17752\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-temple-at-night.jpg 574w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-temple-at-night-300x297.jpg 300w\" sizes=\"(max-width: 574px) 100vw, 574px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c479f24\" data-id=\"c479f24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e36a8c elementor-widget elementor-widget-heading\" data-id=\"2e36a8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Wej\u015bcie do \u015bwi\u0105tyni Ekoin jest pi\u0119knie o\u015bwietlone w nocy<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06e015d elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"06e015d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e7b395 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e7b395\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-794a320\" data-id=\"794a320\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bfcd79 elementor-widget elementor-widget-spacer\" data-id=\"6bfcd79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e44205d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e44205d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19f67ffd\" data-id=\"19f67ffd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c7cff76 elementor-widget elementor-widget-heading\" data-id=\"6c7cff76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Dzien_2_w_Koyasan\"><\/span>Dzie\u0144 2 w Koyasan<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d7c429 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d7c429\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b092e91\" data-id=\"b092e91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0415ce elementor-widget elementor-widget-heading\" data-id=\"f0415ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">PORANEK<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d1cfac1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d1cfac1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-310b806d\" data-id=\"310b806d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eb4f666 elementor-widget elementor-widget-text-editor\" data-id=\"4eb4f666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wczesna pobudka, aby wykorzysta\u0107 mo\u017cliwo\u015b\u0107 wzi\u0119cia udzia\u0142u w bezp\u0142atnych zaj\u0119ciach w \u015bwi\u0105tyni &#8211; porannej modlitwie o 7:00, a nast\u0119pnie w rytuale ognia o 7:30.<\/p>\n<p>\u015aniadanie serwowane jest do pokoju oko\u0142o 8. Podobnie jak obiad, to niesamowita wegetaria\u0144ska uczta.<\/p>\n<p>Po \u015bniadaniu udaj si\u0119 w kierunku Okunoin. Prawie 2-kilometrowego dystansu do mauzoleum nie trzeba pokonywa\u0107 pieszo. My zdecydowali\u015bmy si\u0119 i\u015b\u0107 pieszo i nie \u017ca\u0142owali\u015bmy, poniewa\u017c cmentarz prezentowa\u0142 si\u0119 zupe\u0142nie inaczej w \u015bwietle dziennym. Je\u015bli nie masz ochoty na d\u0142ugi spacer, mo\u017cna dojecha\u0107 autobusem do przystanku Okunoin-mae i przej\u015b\u0107 oko\u0142o kilometra przez nowsz\u0105 cz\u0119\u015b\u0107 cmentarza do bardzo imponuj\u0105cego Torodo Hall, kt\u00f3ry w ci\u0105gu dnia mo\u017cna zwiedza\u0107 w \u015brodku.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5db07a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5db07a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8a0d4a5\" data-id=\"8a0d4a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6796ed6 elementor-widget elementor-widget-heading\" data-id=\"6796ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">\u017cadne z moich zdj\u0119\u0107 nie oddaje prawdziwego pi\u0119kna cmentarza Okunoin<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d19f287 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"d19f287\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-955bbe4\" data-id=\"955bbe4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-536d042 elementor-widget elementor-widget-image\" data-id=\"536d042\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Okunoin-Cementary-Koyasan-2-day-itinerary-betifulworld-e1687343988511.jpg\" class=\"attachment-large size-large wp-image-17704\" alt=\"Okunoin Cementary Koyasan 2 day itinerary betifulworld\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98d61d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98d61d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6703c47\" data-id=\"6703c47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a6c1d0 elementor-widget elementor-widget-spacer\" data-id=\"6a6c1d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2af0ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2af0ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9bedc7d\" data-id=\"9bedc7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d8cda6 elementor-widget elementor-widget-text-editor\" data-id=\"4d8cda6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Po zwiedzeniu Okunoin wsi\u0105d\u017a do autobusu na przystanku Okunoin-mae i udaj si\u0119 w kierunku Daimon Gate.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12e6450 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12e6450\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a025cad\" data-id=\"a025cad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-040a1be elementor-widget elementor-widget-heading\" data-id=\"040a1be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">OBIAD<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f385f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f385f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0caa1b7\" data-id=\"0caa1b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c0e7cb elementor-widget elementor-widget-text-editor\" data-id=\"1c0e7cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Zatrzymali\u015bmy si\u0119 <\/span><span style=\"font-weight: 400;\">na obiad<\/span><span style=\"font-weight: 400;\"> w ma\u0142ej restauracji o nazwie <em>Tsukumo<\/em> znajduj\u0105cej si\u0119 niedaleko Bramy Daimon. Mia\u0142a dobre recenzje online i podoba\u0142o nam si\u0119 zar\u00f3wno lokalne jedzenie, jak i tradycyjny styl wn\u0119trza. Zostali\u015bmy skierowani do sto\u0142u, aby usi\u0105\u015b\u0107 na macie tatami (<\/span><span style=\"font-weight: 400;\">dla tradycjonalist\u00f3w<\/span><span style=\"font-weight: 400;\"> s\u0105 te\u017c normalne sto\u0142y) i obserwowali\u015bmy mnich\u00f3w ciesz\u0105cych si\u0119 przerw\u0105 na lunch. Pewnie po\u015bcili, skoro dostali dwa dania g\u0142\u00f3wne, kt\u00f3re \u201cpo\u017carli\u201d chyba w dwie minuty! Nasze dania zaserwowano szybko &#8211; pilaw z ry\u017cu warzywnego &#8211; specjalno\u015b\u0107 restauracji <\/span><span style=\"font-weight: 400;\">&#8211;<\/span><span style=\"font-weight: 400;\"> i zupa udon z wo\u0142owin\u0105, oba by\u0142y smaczne i tanie. Je\u015bli chcesz zje\u015b\u0107 <\/span><span style=\"font-weight: 400;\">miejscowe potrawy w lokalnej atmosferze<\/span><span style=\"font-weight: 400;\">, \u201cTsukumo\u201d to \u015bwietny wyb\u00f3r. Pami\u0119taj, \u017ce przygotowanie pilawu z mi\u0119sem wo\u0142owym zajmuje ponad 35 minut, wi\u0119c mo\u017ce warto wybra\u0107 warzywn\u0105 opcj\u0119 lub zup\u0119, je\u015bli zale\u017cy Ci na mi\u0119sie.<\/span><\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/goo.gl\/maps\/iG46DWv1TQsSJxD96\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\"><strong>Restauracja Tsukumo &#8211; Lokalizacja na Mapach Google\u00a0<\/strong><\/span><\/a><\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8de983f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8de983f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc5b7f8\" data-id=\"dc5b7f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-512fd81 elementor-widget elementor-widget-heading\" data-id=\"512fd81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">POPO\u0141UDNIE<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86ff68b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86ff68b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-527dcd1\" data-id=\"527dcd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a94a36 elementor-widget elementor-widget-text-editor\" data-id=\"4a94a36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Z pe\u0142nym brzuchem i dobrze wypocz\u0119ci udajcie si\u0119 do imponuj\u0105cej <\/span><b>Bramy Daimon<\/b><span style=\"font-weight: 400;\">, g\u0142\u00f3wnego wej\u015bci<\/span><span style=\"font-weight: 400;\">a<\/span><span style=\"font-weight: 400;\"> do Koyasan, kt\u00f3rego strze\u017ce dw\u00f3ch gro\u017anych stra\u017cnik\u00f3w.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2aa31fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2aa31fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97329da\" data-id=\"97329da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33a00c1 elementor-widget elementor-widget-heading\" data-id=\"33a00c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">WSKAZ\u00d3WKA #4 - ZWIEDZANIE BRAMY DAIMONA <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-463ac6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"463ac6c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b966fc8\" data-id=\"b966fc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca634c1 elementor-widget elementor-widget-text-editor\" data-id=\"ca634c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Je\u015bli planujecie w\u0119dr\u00f3wk\u0119 <strong>Pielgrzymkowym Szlakiem Kobiet<\/strong>, rano mo\u017cecie pomin\u0105\u0107 poranne zwiedzanie bramy, poniewa\u017c b\u0119dziecie j\u0105 mija\u0107 pod koniec w\u0119dr\u00f3wki.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-299b7b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"299b7b0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed92b00\" data-id=\"ed92b00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab6ab8d elementor-widget elementor-widget-heading\" data-id=\"ab6ab8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Ostatnia brama torii ko\u0144cz\u0105ca 2-kilometrow\u0105 w\u0119dr\u00f3wk\u0119 znajduje si\u0119 tu\u017c przy Bramie Daimona<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f5ea21 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"4f5ea21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9acbed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9acbed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-88e89c5\" data-id=\"88e89c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b1c58f elementor-widget elementor-widget-image\" data-id=\"4b1c58f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"701\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Hiking-Koyasan-2-day-itinerary.jpg\" class=\"attachment-large size-large wp-image-17675\" alt=\"Hiking - Koyasan 2 day itinerary\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Hiking-Koyasan-2-day-itinerary.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Hiking-Koyasan-2-day-itinerary-257x300.jpg 257w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-af8608d\" data-id=\"af8608d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab59be9 elementor-widget elementor-widget-image\" data-id=\"ab59be9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"700\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Daimon-Gate-Koyasan-2-day-itinerary.jpg\" class=\"attachment-large size-large wp-image-17677\" alt=\"Daimon Gate - Koyasan 2 day itinerary\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Daimon-Gate-Koyasan-2-day-itinerary.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Daimon-Gate-Koyasan-2-day-itinerary-257x300.jpg 257w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-355a693 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"355a693\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7532b1\" data-id=\"d7532b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3990aba elementor-widget elementor-widget-spacer\" data-id=\"3990aba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ec70ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ec70ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88bdf00\" data-id=\"88bdf00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7a8b29 elementor-widget elementor-widget-heading\" data-id=\"d7a8b29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">NAJLEPSZA KAWA W KOYASAN<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26f6f71b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26f6f71b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-562d531e\" data-id=\"562d531e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47563c04 elementor-widget elementor-widget-text-editor\" data-id=\"47563c04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Zatrzymaj si\u0119 na kaw\u0119 w <em>Powerstone &amp; Cafe Shinsei<\/em>, kawiarence, kt\u00f3ra znajduje si\u0119 przy g\u0142\u00f3wnej drodze mi\u0119dzy Daimon Gate a kompleksem \u015bwi\u0105tynnym Danjo Garan. T<\/span><span style=\"font-weight: 400;\">a<\/span><span style=\"font-weight: 400;\"> ma\u0142a urocza kawiarnia serwuje bardzo dobr\u0105 kaw\u0119, zar\u00f3wno caffe latte z mlekiem sojowym, jak i zwyk\u0142e cappuccino by\u0142y pyszne. Wypicie kawy przy stoliku na zewn\u0105trz i obserwowanie up\u0142ywu czasu w ma\u0142ym miasteczku Koyasan powinno zdecydowanie znale\u017a\u0107 si\u0119 na Twojej \u201eli\u015bcie rzeczy do zrobienia\u201d.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d72690a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d72690a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-88817cc\" data-id=\"88817cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1727616 elementor-widget elementor-widget-image\" data-id=\"1727616\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"748\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Powerstone-Cafe-Shinsei-coffee-in-Koyasan-.jpg\" class=\"attachment-large size-large wp-image-17578\" alt=\"Powerstone &amp; Cafe Shinsei - coffee in Koyasan\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Powerstone-Cafe-Shinsei-coffee-in-Koyasan-.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Powerstone-Cafe-Shinsei-coffee-in-Koyasan--241x300.jpg 241w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5591942\" data-id=\"5591942\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d7c5fc elementor-widget elementor-widget-heading\" data-id=\"7d7c5fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Czasami ma\u0142a przerwa na trasie zapada bardziej w pami\u0119\u0107 ni\u017c nawet najpi\u0119kniejsza \u015bwi\u0105tynia...<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed89f26 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"ed89f26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b49615f elementor-widget elementor-widget-heading\" data-id=\"b49615f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">...zw\u0142aszcza je\u015bli sp\u0119dzasz j\u0105 w towarzystwie rodziny Tanuki \ud83d\ude42<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8adbd91\" data-id=\"8adbd91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4981b9 elementor-widget elementor-widget-image\" data-id=\"d4981b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"750\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Powerstone-Cafe-Shinsei-Koyasan-.jpg\" class=\"attachment-large size-large wp-image-17580\" alt=\"Powerstone &amp; Cafe Shinsei Koyasan\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Powerstone-Cafe-Shinsei-Koyasan-.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Powerstone-Cafe-Shinsei-Koyasan--240x300.jpg 240w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0f2612 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0f2612\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8a9799\" data-id=\"e8a9799\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3297b8 elementor-widget elementor-widget-spacer\" data-id=\"a3297b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9834c00 elementor-widget elementor-widget-text-editor\" data-id=\"9834c00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/goo.gl\/maps\/KfQoYidtUYLqkorY7\" target=\"_blank\" rel=\"noopener\"><b>Powerstone &amp; Cafe Shinsei &#8211; [LOKALIZACJA NA MAPACH\u00a0 GOOGLE]<\/b><\/a><\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14238cd elementor-widget elementor-widget-spacer\" data-id=\"14238cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-696c4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"696c4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60b5771f\" data-id=\"60b5771f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56f6fc5d elementor-widget elementor-widget-heading\" data-id=\"56f6fc5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">NAJWA\u017bNIEJSZE \u015aWI\u0104TYNIE W KOYASAN<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25cc99c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25cc99c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a37e473\" data-id=\"a37e473\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27265b08 elementor-widget elementor-widget-text-editor\" data-id=\"27265b08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Po kawce skieruj si\u0119 do <\/span><b>Danjo Garan<\/b><span style=\"font-weight: 400;\">, przestronnego kompleksu \u015bwi\u0105tynn<\/span><span style=\"font-weight: 400;\">ego,<\/span><span style=\"font-weight: 400;\"> otoczonego pi\u0119knymi cedrami. Zwied\u017a g\u0142\u00f3wn\u0105 sal\u0119 i pagod\u0119 wewn\u0105trz po uiszczeniu op\u0142aty za wst\u0119p lub podziwiaj majestatyczne budynki tylko z zewn\u0105trz. Obiecuj\u0119 &#8211; tak czy siak b\u0119dzie pi\u0119knie.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7899f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7899f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1a0c76f\" data-id=\"1a0c76f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb4b660 elementor-widget elementor-widget-image\" data-id=\"cb4b660\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-entrance.jpg\" class=\"attachment-large size-large wp-image-17626\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-entrance.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-entrance-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e4326a6\" data-id=\"e4326a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bcc156 elementor-widget elementor-widget-image\" data-id=\"9bcc156\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-trees.jpg\" class=\"attachment-large size-large wp-image-17634\" alt=\"Danjo Garan Temple Complex trees\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-trees.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-trees-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4b42e86\" data-id=\"4b42e86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51ad7b0 elementor-widget elementor-widget-image\" data-id=\"51ad7b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-entrance-guardians.jpg\" class=\"attachment-large size-large wp-image-17632\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-entrance-guardians.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Danjo-Garan-Temple-Complex-entrance-guardians-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70c77fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70c77fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8b7b06\" data-id=\"d8b7b06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c88fd9 elementor-widget elementor-widget-text-editor\" data-id=\"1c88fd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Po wizycie w Danjo Garan udaj si\u0119 do <\/span><strong>\u015b<\/strong><b>wi\u0105tyni Kongobuji<\/b><span style=\"font-weight: 400;\">, siedziba buddyzmu Shingon. Zwied\u017a ogr\u00f3d skalny \u015bwi\u0105tyni i zobacz s\u0142ynne malowid\u0142a na przesuwanych drzwiach.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">Ze <\/span><b>\u015b<\/b><b>wi\u0105tyni Kongobuji<\/b><span style=\"font-weight: 400;\"> w 5 minut autobusem dojedziesz do <\/span><b>Nyonindo Hall,<\/b><span style=\"font-weight: 400;\"> zbudowanego na potrzeby kobiet, kt\u00f3re pomimo zabronionego przed rokiem 1872 wst\u0119pu do Koyasan, przyby\u0142y w te strony.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3907bb61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3907bb61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3281b290\" data-id=\"3281b290\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74e0853b elementor-widget elementor-widget-heading\" data-id=\"74e0853b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">PRZYJEMNA G\u00d3RSKA W\u0118DR\u00d3WKA NA ZAKO\u0143CZENIE PI\u0118KNEGO DNIA<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21330af5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21330af5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f9095f7\" data-id=\"1f9095f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-609bd8d4 elementor-widget elementor-widget-text-editor\" data-id=\"609bd8d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Szlak pn\u0105cy si\u0119 w g\u00f3r\u0119 przed <\/span><b>Nyonindo Hall <\/b>jest <span style=\"font-weight: 400;\">to pocz\u0105tek <\/span><b>Women Pilgrims Course<\/b><span style=\"font-weight: 400;\">. Pocz\u0105tkowo \u015bcie\u017cka mo\u017ce wygl\u0105da\u0107 troch\u0119 przera\u017caj\u0105co, ale nie martw si\u0119 zbytnio, tylko kilka pierwszych metr\u00f3w jest nieco strome. Og\u00f3lnie rzecz bior\u0105c, jest to przyjemny spacer po lesie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Po oko\u0142o godzinie dotrzesz do Daimon Gate, sk\u0105d autobusem dojedziesz do \u015bwi\u0105tyni Ekoin lub innego miejsca, w kt\u00f3rym zostawi\u0142e\u015b baga\u017c, aby go odebra\u0107 i wsi\u0105\u015b\u0107 do autobusu w kierunku stacji Koyasan, aby rozpocz\u0105\u0107 podr\u00f3\u017c z powrotem do cywilizacji, do Osaki lub twojego nast\u0119pnego celu podr\u00f3\u017cy.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee0f62c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee0f62c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d55bf99\" data-id=\"d55bf99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0940fd elementor-widget elementor-widget-image\" data-id=\"d0940fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-hiking-red-torii.jpg\" class=\"attachment-large size-large wp-image-17684\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-hiking-red-torii.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-hiking-red-torii-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-57fa5aa\" data-id=\"57fa5aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3674ee elementor-widget elementor-widget-heading\" data-id=\"f3674ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Koyasan o 16:00 i Osaka o 19:00... Dlaczego wszystko, co dobre, musi si\u0119 sko\u0144czy\u0107?<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94ea566 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"94ea566\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-33f4ac9\" data-id=\"33f4ac9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0c4205 elementor-widget elementor-widget-image\" data-id=\"f0c4205\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Osaka-Metro.jpg\" class=\"attachment-large size-large wp-image-17686\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Osaka-Metro.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Osaka-Metro-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86a85ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86a85ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34c5dd9\" data-id=\"34c5dd9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff69c0b elementor-widget elementor-widget-spacer\" data-id=\"ff69c0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43fb17e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43fb17e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3be2c25\" data-id=\"3be2c25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5161381 elementor-widget elementor-widget-heading\" data-id=\"5161381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">WSKAZ\u00d3WKA #5 - OSTATNI AUTOBUS W KOYASAN<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42fa1c2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42fa1c2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50f7cdc5\" data-id=\"50f7cdc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5101f972 elementor-widget elementor-widget-text-editor\" data-id=\"5101f972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ostatni autobus z Daimon Gate w kierunku \u015bwi\u0105tyni Okunoin, zatrzymuj\u0105cy si\u0119 przed \u015bwi\u0105tyni\u0105 Ekoin, odje\u017cd\u017ca oko\u0142o 15:00. Je\u015bli tak jak my dotrzesz na przystanek p\u00f3\u017aniej, b\u0119dziesz musia\u0142 i\u015b\u0107 pieszo lub spr\u00f3bowa\u0107 wzi\u0105\u0107 taks\u00f3wk\u0119. My wybrali\u015bmy spacer do \u015bwi\u0105tyni Ekoin g\u0142\u00f3wn\u0105 drog\u0105 (~25 min).<\/span><\/p>\n<p>Natomiast ostatni autobus w kierunku stacji Koyasan odje\u017cd\u017ca znacznie p\u00f3\u017aniej, po 21:00.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3eb4e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3eb4e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1564e5a\" data-id=\"1564e5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da63870 elementor-widget elementor-widget-heading\" data-id=\"da63870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">G\u0142\u00f3wna droga w Koyasan <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-157ee1b elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"157ee1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da4e1de\" data-id=\"da4e1de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41a35dd elementor-widget elementor-widget-image\" data-id=\"41a35dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"677\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-main-road.jpg\" class=\"attachment-large size-large wp-image-17679\" alt=\"Koyasan main road\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-main-road.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-main-road-266x300.jpg 266w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cfa994 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cfa994\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96622e9\" data-id=\"96622e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ecfbc6 elementor-widget elementor-widget-spacer\" data-id=\"1ecfbc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-179e53d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"179e53d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-338fbcb9\" data-id=\"338fbcb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c464877 elementor-widget elementor-widget-heading\" data-id=\"c464877\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">WSKAZ\u00d3WKA #6 - JAK ZAPLANOWA\u0106 TRAS\u0118? <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2aa72da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2aa72da\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22bea763\" data-id=\"22bea763\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bf1fb2c elementor-widget elementor-widget-text-editor\" data-id=\"7bf1fb2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Je\u015bli jeste\u015bcie w 100% pewni, \u017ce chcecie si\u0119 <strong>Pielgrzymkowym Szlakiem Kobiet <\/strong><\/span><span style=\"font-weight: 400;\">wybra\u0107, mo\u017cecie rozpocz\u0105\u0107 dzie\u0144 od le\u015bnej w\u0119dr\u00f3wki. My zostawili\u015bmy wycieczk\u0119 na \u0142ono natury na koniec dnia, poniewa\u017c naszym g\u0142\u00f3wnym celem by\u0142y \u015bwi\u0105tynie i nie wiedzieli\u015bmy, ile czasu zajmie ich zwiedzenie. Poza tym fajnie by\u0142o odpocz\u0105\u0107 na \u0142onie natury po troch\u0119 wyczerpuj\u0105cym zwiedzaniu zabytk\u00f3w. Patrz\u0105c wstecz, jest czas na wszystko, poniewa\u017c i tak wcze\u015bnie zaczniesz dzie\u0144 w \u015bwi\u0105tyni, wi\u0119c kolejno\u015b\u0107 zwiedzania zale\u017cy wy\u0142\u0105cznie od Ciebie.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52dafd04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52dafd04\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-724c5d0e\" data-id=\"724c5d0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50fa4c63 elementor-widget elementor-widget-heading\" data-id=\"50fa4c63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"NOCLEG_W_BUDDYJSKIEJ_SWIATYNI_W_JAPONII_CZEGO_SIE_SPODZIEWAC\"><\/span>NOCLEG W BUDDYJSKIEJ \u015aWI\u0104TYNI W JAPONII: CZEGO SI\u0118 SPODZIEWA\u0106?<span class=\"ez-toc-section-end\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e9f324 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e9f324\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-770879c5\" data-id=\"770879c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29735be6 elementor-widget elementor-widget-text-editor\" data-id=\"29735be6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ta cz\u0119\u015b\u0107 jest bardzo subiektywna, poniewa\u017c moje wra\u017cenia uwarunkowane s\u0105 moimi wcze\u015bniejszymi do\u015bwiadczeniami. Tw\u00f3j pobyt w <\/span><span style=\"font-weight: 400;\">\u015b<\/span><span style=\"font-weight: 400;\">wi\u0105tyni Ekoin mo\u017ce wygl\u0105da\u0107 zupe\u0142nie inaczej.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Chc\u0105c nie chc\u0105c, przyjecha\u0142am do \u015bwi\u0105tyni Ekoin z pewnymi oczekiwaniami. Po pierwsze, <\/span><span style=\"font-weight: 400;\">pobyt w<\/span><span style=\"font-weight: 400;\"> Koyasan by\u0142 moim drugim pobytem w \u015bwi\u0105tyni w Japonii. W pa\u017adzierniku ubieg\u0142ego roku odwiedzi\u0142<\/span><span style=\"font-weight: 400;\">a<\/span><span style=\"font-weight: 400;\">m Takayam\u0119, gdzie zatrzyma\u0142<\/span><span style=\"font-weight: 400;\">a<\/span><span style=\"font-weight: 400;\">m si\u0119 w Temple Hotel Takayama Zenkoji, gdzie <\/span><span style=\"font-weight: 400;\">ogromnie<\/span><span style=\"font-weight: 400;\"> mi si\u0119 podoba\u0142o. Po drugie, przez ostatnie 3 lata mia\u0142am okazj\u0119 zatrzyma\u0107 si\u0119 w wielu tradycyjnych pensjonatach w odleg\u0142ych zak\u0105tkach Japonii. Moje oczekiwania by\u0142y wi\u0119c prawdopodobnie bardzo odmienne od tych, kt\u00f3re ma osoba odwiedzaj\u0105ca Japoni\u0119 po raz pierwszy. Mo\u017ce do ko\u0144ca nie by\u0142am zachwycona tym do\u015bwiadczeniem, ale nadal uwa\u017cam, \u017ce jest za bardzo wyj\u0105tkowe, i nie \u017ca\u0142uj\u0119.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f7d3cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f7d3cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6650d77\" data-id=\"6650d77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59e7ae2 elementor-widget elementor-widget-heading\" data-id=\"59e7ae2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Witajcie w \u015bwi\u0105tyni Ekoin w Koyasan!<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8ef64 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"1e8ef64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b238950 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b238950\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-095a728\" data-id=\"095a728\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52d663a elementor-widget elementor-widget-image\" data-id=\"52d663a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Temple-Stay-at-Ekoin-temple.jpg\" class=\"attachment-large size-large wp-image-17777\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Temple-Stay-at-Ekoin-temple.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Temple-Stay-at-Ekoin-temple-300x300.jpg 300w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Temple-Stay-at-Ekoin-temple-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0d5598f\" data-id=\"0d5598f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-081243e elementor-widget elementor-widget-image\" data-id=\"081243e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-Temple-Stay-Review-monks-e1687350698417.jpg\" class=\"attachment-large size-large wp-image-17718\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3795497 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3795497\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-938a941\" data-id=\"938a941\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fd1317 elementor-widget elementor-widget-spacer\" data-id=\"4fd1317\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e12d6e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e12d6e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47b84d47\" data-id=\"47b84d47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79f1cc76 elementor-widget elementor-widget-heading\" data-id=\"79f1cc76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Pozytywne_strony_pobytu_w_swiatyni_w_Koyasan\"><\/span>Pozytywne strony pobytu w \u015bwi\u0105tyni w Koyasan<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54e276ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54e276ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3118781\" data-id=\"3118781\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a31166 elementor-widget elementor-widget-heading\" data-id=\"2a31166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">PI\u0118KNE WN\u0118TRZA \u015aWI\u0104TYNI EKOIN<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79f307ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79f307ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-538bac87\" data-id=\"538bac87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b76f1bb elementor-widget elementor-widget-text-editor\" data-id=\"2b76f1bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Szczeg\u00f3lnie przypad\u0142 mi do gustu d\u0142ugi hall z przestronnymi pokojami z pi\u0119knie pomalowanymi przesuwnymi drzwiami<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> prowadz\u0105cy z recepcji do pokoju. G\u0142\u00f3wna \u015bwi\u0105tynia, w kt\u00f3rej odbywaj\u0105 si\u0119 poranne modlitwy, jest r\u00f3wnie\u017c przepi\u0119kna i macie szans\u0119 wej\u015b\u0107 do \u015bwi\u0119tej jej cz\u0119\u015bci, <\/span><span style=\"font-weight: 400;\">zwykle<\/span><span style=\"font-weight: 400;\"> niedost\u0119pnej dla turyst\u00f3w w innych \u015bwi\u0105tyniach.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e93ef11 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e93ef11\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aba7bad\" data-id=\"aba7bad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ff2002 elementor-widget elementor-widget-image\" data-id=\"6ff2002\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-Koyasan-interiors.jpg\" class=\"attachment-large size-large wp-image-17550\" alt=\"Ekoin Temple Koyasan - interiors\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-Koyasan-interiors.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-Koyasan-interiors-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8ce1c62\" data-id=\"8ce1c62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38b3a8e elementor-widget elementor-widget-image\" data-id=\"38b3a8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-interiors.jpg\" class=\"attachment-large size-large wp-image-17552\" alt=\"Ekoin Temple - interiors\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-interiors.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-interiors-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d82cd8d\" data-id=\"d82cd8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-117b0be elementor-widget elementor-widget-image\" data-id=\"117b0be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-Koyasan-interior.jpg\" class=\"attachment-large size-large wp-image-17548\" alt=\"Ekoin Temple Koyasan - interior\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-Koyasan-interior.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-Koyasan-interior-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7767f25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7767f25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50da527\" data-id=\"50da527\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fd5409 elementor-widget elementor-widget-spacer\" data-id=\"6fd5409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e6a93f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6a93f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33da16e\" data-id=\"33da16e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e7dbce elementor-widget elementor-widget-text-editor\" data-id=\"0e7dbce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Pokoje w stylu japo\u0144skim s\u0105 przestronne i daj\u0105 mo\u017cliwo\u015b\u0107 spania na tradycyjnym japo\u0144skim materacu (<em>futon<\/em><\/span><span style=\"font-weight: 400;\">),<\/span><span style=\"font-weight: 400;\"> u\u0142o\u017conym na macie tatami. Mieszkali\u015bmy w prostym pokoju ze wsp\u00f3ln\u0105 toalet\u0105, ale dost\u0119pne s\u0105 r\u00f3wnie\u017c pokoje z prywatn\u0105 \u0142azienk\u0105 oraz luksusowy apartament.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b5276eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b5276eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62360de0\" data-id=\"62360de0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-193e9d1 elementor-widget elementor-widget-heading\" data-id=\"193e9d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">WCZESNY CHECK-IN<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b34369a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b34369a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48a175f9\" data-id=\"48a175f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2157b663 elementor-widget elementor-widget-text-editor\" data-id=\"2157b663\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Check-in w Ekoin Temple jest mo\u017cliw<\/span><span style=\"font-weight: 400;\">y<\/span><span style=\"font-weight: 400;\"> od godziny 13:00, co jest \u015bwietne, poniewa\u017c mo\u017cesz d\u0142u\u017cej cieszy\u0107 si\u0119 otoczeniem \u015bwi\u0105tyni i swoim pokojem. W Japonii zameldowanie odbywa si\u0119 zwykle od 16:00, a czasem nawet p\u00f3\u017aniej, wi\u0119c jest to bardzo hojne ze strony mnich\u00f3w. Spr\u00f3buj wi\u0119c zameldowa\u0107 si\u0119 wcze\u015bniej lub przynajmniej przed 16:00, aby wzi\u0105\u0107 udzia\u0142 w bezp\u0142atnej medytacji.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c4826e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c4826e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81a8f33\" data-id=\"81a8f33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8586991 elementor-widget elementor-widget-heading\" data-id=\"8586991\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">BEZP\u0141ATNE ZAJ\u0118CIA DLA GO\u015aCI \u015aWI\u0104TYNI DOST\u0118PNE CODZIENNIE<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33ba5757 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33ba5757\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-334634c6\" data-id=\"334634c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42aa9606 elementor-widget elementor-widget-text-editor\" data-id=\"42aa9606\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">40-minutowa medytacja od 16:30 przez oko\u0142o 40 minut. Niestety<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> nie uda\u0142o nam si\u0119 zameldowa\u0107 przed 17:00 i nie mogli\u015bmy w niej uczestniczy\u0107.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Poranne modlitwy w intencji buddyjskich \u015bwi\u0119tych od 7 rano przez oko\u0142o 25 minut. \u015apiewanie mnich\u00f3w jest jednocze\u015bnie pot\u0119\u017cnym i relaksuj\u0105cym prze\u017cyciem.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Rytua\u0142 konsekrowanego ognia \u201cGoma\u201d, kt\u00f3ry, jak si\u0119 uwa\u017ca, ma dzia\u0142anie oczyszczaj\u0105ce zar\u00f3wno duchowo i psychicznie, rozpoczyna si\u0119 o 7:30 i trwa oko\u0142o 30 minut.<\/span><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2077280 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2077280\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c1d149\" data-id=\"3c1d149\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f15828 elementor-widget elementor-widget-heading\" data-id=\"5f15828\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Spektakularny Rytua\u0142 Ognia, odbywaj\u0105cy si\u0119 w \u015bwi\u0105tyni Bishamondo, kt\u00f3ra podobno zosta\u0142a zbudowana przez Kobo Daishi, jest g\u0142\u00f3wn\u0105 atrakcj\u0105 pobytu w \u015bwi\u0105tyni Ekoin w Koyasan.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5c423a elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"b5c423a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f39a111 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f39a111\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b318e0\" data-id=\"4b318e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a49814 elementor-widget elementor-widget-image\" data-id=\"1a49814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"699\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-Ekoin-Temple-Fire-Ritual.jpg\" class=\"attachment-large size-large wp-image-17526\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-Ekoin-Temple-Fire-Ritual.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-Ekoin-Temple-Fire-Ritual-258x300.jpg 258w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da2ced1\" data-id=\"da2ced1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abf08cd elementor-widget elementor-widget-image\" data-id=\"abf08cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"699\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-Ekoin-Temple.jpg\" class=\"attachment-large size-large wp-image-17528\" alt=\"Koyasan temple stay - Ekoin Temple\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-Ekoin-Temple.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-Ekoin-Temple-258x300.jpg 258w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4709fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4709fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7342817\" data-id=\"7342817\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74fe4e2 elementor-widget elementor-widget-spacer\" data-id=\"74fe4e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3331184 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3331184\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7931fc2\" data-id=\"7931fc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c8ff60 elementor-widget elementor-widget-text-editor\" data-id=\"1c8ff60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/fb.watch\/l6dnYH4kSG\/\" target=\"_blank\" rel=\"noopener\">Kr\u00f3tki film z Rytua\u0142u Ogna, w kt\u00f3rym brali\u015bmy udzia\u0142 [KLIKNIJ TUTAJ]<\/a><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nawet je\u015bli <\/span><span style=\"font-weight: 400;\">T<\/span><span style=\"font-weight: 400;\">woja wiedza na temat buddyzmu jest ograniczona, warto wzi\u0105\u0107 udzia\u0142 w tych zaj\u0119ciach, poniewa\u017c to w\u0142a\u015bnie one sprawiaj\u0105, \u017ce pobyt w \u015bwi\u0105tyni w Koyasan jest tak wyj\u0105tkow<\/span><span style=\"font-weight: 400;\">y<\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45b27a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45b27a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd6bd23\" data-id=\"cd6bd23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d35a32 elementor-widget elementor-widget-heading\" data-id=\"7d35a32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">KUCHNIA BUDDYJSKA (SHOJIN RYORI)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6cc97b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6cc97b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-edaec41\" data-id=\"edaec41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65b25e2 elementor-widget elementor-widget-text-editor\" data-id=\"65b25e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nawet je\u015bli nie jeste\u015b wielkim mi\u0142o\u015bnikiem wegetarian i tofu, prawdopodobnie spodoba ci si\u0119 cudowna uczta. Sk\u0142adniki s\u0105 starannie dobrane i przygotowane do perfekcji, a prezentacja jedzenia <\/span><span style=\"font-weight: 400;\">wygl\u0105da<\/span><span style=\"font-weight: 400;\"> jak w najbardziej eleganckiej restauracji.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec2a420 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec2a420\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a28c437\" data-id=\"a28c437\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eb9796 elementor-widget elementor-widget-heading\" data-id=\"4eb9796\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Czas na kolacj\u0119!<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df4b02f elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"df4b02f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54fbed2 elementor-widget elementor-widget-image\" data-id=\"54fbed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-Ekoin-Temple-dinner.jpg\" class=\"attachment-large size-large wp-image-17530\" alt=\"2-day Koyasan temple stay - Ekoin Temple dinner\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-Ekoin-Temple-dinner.jpg 800w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-Ekoin-Temple-dinner-300x225.jpg 300w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/2-day-Koyasan-temple-stay-Ekoin-Temple-dinner-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e2e7a97\" data-id=\"e2e7a97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e452ca elementor-widget elementor-widget-image\" data-id=\"2e452ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-dinner-served-in-the-room-e1687320710675.jpg\" class=\"attachment-large size-large wp-image-17559\" alt=\"Ekoin Temple - dinner served in the room\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed0f20d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed0f20d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9b8d444\" data-id=\"9b8d444\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0052a4e elementor-widget elementor-widget-spacer\" data-id=\"0052a4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e80842c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e80842c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32b5ac6\" data-id=\"32b5ac6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-123cc39 elementor-widget elementor-widget-heading\" data-id=\"123cc39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Mniej_pozytywne_strony_pobytu_w_swiatyni_Ekoin\"><\/span>Mniej pozytywne strony pobytu w \u015bwi\u0105tyni Ekoin <span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76b8fd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76b8fd6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63d3b2b\" data-id=\"63d3b2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-854dfa5 elementor-widget elementor-widget-heading\" data-id=\"854dfa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">KOMERCJALIZACJA<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-182b6bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"182b6bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac45fbc\" data-id=\"ac45fbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2caf52d elementor-widget elementor-widget-text-editor\" data-id=\"2caf52d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Pierwsz\u0105 rzecz\u0105, kt\u00f3r\u0105 ujrza\u0142am<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> wchodz\u0105c przez bram\u0119 \u015bwi\u0105tyni, by\u0142 food truck sprzedaj\u0105cy krokiety wo\u0142owe na dziedzi\u0144cu \u015bwi\u0105tyni. Telewizor w pokoju i mo\u017cliwo\u015b\u0107 zam\u00f3wienia napoj\u00f3w alkoholowych do <\/span><span style=\"font-weight: 400;\">tego\u017c<\/span><span style=\"font-weight: 400;\"> pokoju nie do ko\u0144ca pasowa\u0142y mi <\/span><span style=\"font-weight: 400;\">d<\/span><span style=\"font-weight: 400;\">o pobytu w buddyjskiej \u015bwi\u0105tyni w Japonii. Oczywi\u015bcie<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> nie musisz w\u0142\u0105cza\u0107 telewizora ani zamawia\u0107 piwa rzemie\u015blniczego, ale gdyby tych opcji nie by\u0142o, by\u0142oby to dla mnie bardziej autentyczne do\u015bwiadczenie.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e7cece elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e7cece\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-87dd50f\" data-id=\"87dd50f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57c265b elementor-widget elementor-widget-heading\" data-id=\"57c265b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">\u201eniezupe\u0142nie to, czego spodziewa\u0142am si\u0119 ujrze\u0107 w 1000-letniej \u015bwi\u0105tyni\u2026\u201d<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb6f38d elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"bb6f38d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cfbc704\" data-id=\"cfbc704\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ab170b elementor-widget elementor-widget-image\" data-id=\"2ab170b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-entrance.jpg\" class=\"attachment-large size-large wp-image-17505\" alt=\"Ekoin Temple - entrance\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-entrance.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-entrance-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9acfd8f\" data-id=\"9acfd8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c01f51 elementor-widget elementor-widget-image\" data-id=\"3c01f51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-food-track.jpg\" class=\"attachment-large size-large wp-image-17507\" alt=\"Ekoin Temple - food track\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-food-track.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-food-track-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b85cac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b85cac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-08fc629\" data-id=\"08fc629\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6c7c7c elementor-widget elementor-widget-image\" data-id=\"f6c7c7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-room-with-TV.jpg\" class=\"attachment-large size-large wp-image-17509\" alt=\"\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-room-with-TV.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-room-with-TV-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f6625ca\" data-id=\"f6625ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-526f5b5 elementor-widget elementor-widget-image\" data-id=\"526f5b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-Menu.jpg\" class=\"attachment-large size-large wp-image-17511\" alt=\"Ekoin Temple Menu\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-Menu.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Ekoin-Temple-Menu-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0da57a1\" data-id=\"0da57a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-406685a elementor-widget elementor-widget-heading\" data-id=\"406685a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">\u201e...a mo\u017ce tylko ja jestem wybredna?\u201d<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40fc9bb elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"40fc9bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60238a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60238a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4910c6e\" data-id=\"4910c6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a99bbd1 elementor-widget elementor-widget-spacer\" data-id=\"a99bbd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abacfde elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abacfde\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-755b773\" data-id=\"755b773\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92100a0 elementor-widget elementor-widget-heading\" data-id=\"92100a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">MNISI POD PRESJ\u0104 CZASU<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b56950 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b56950\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41598a9\" data-id=\"41598a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f2435d elementor-widget elementor-widget-text-editor\" data-id=\"7f2435d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Mnisi zawsze si\u0119 spieszyli. Cho\u0107 w \u015bwi\u0105tyni by\u0142o ich wielu, prawdopodobnie wci\u0105\u017c by\u0142o ich za ma\u0142o w stosunku do liczby go\u015bci. Od buddyjskich mnich\u00f3w spodziewa\u0142am si\u0119 du\u017co cierpliwo\u015bci i spokoju ducha, ale poniewa\u017c wydawali si\u0119 by\u0107 pod du\u017c\u0105 presj\u0105 czasu, to wygl\u0105dali na troszk\u0119 zestresowanych. Nie by<\/span><span style=\"font-weight: 400;\">\u0142a<\/span><span style=\"font-weight: 400;\"> to do ko\u0144ca atmosfera, jakiej oczekiwa\u0142am w \u015bwi\u0105tyni buddyjskiej.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dda5fdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dda5fdf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5bbf23\" data-id=\"e5bbf23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c264d6 elementor-widget elementor-widget-heading\" data-id=\"8c264d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Napi\u0119ty harmonogram mnicha: ten sam mnich, kt\u00f3ry prowadzi\u0142 Rytua\u0142 Ognia, wykonywa\u0142 wiele przyziemnych zada\u0144. Pom\u00f3g\u0142 nam zarezerwowa\u0107 wycieczk\u0119 po cmentarzu i pomaga\u0142 w sprz\u0105taniu pokoi.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ef2d5e elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"3ef2d5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9358faf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9358faf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6854f02\" data-id=\"6854f02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43d61d7 elementor-widget elementor-widget-image\" data-id=\"43d61d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-review-.jpg\" class=\"attachment-large size-large wp-image-17518\" alt=\"Koyasan temple stay review\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-review-.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-review--300x300.jpg 300w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-review--150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-98d1896\" data-id=\"98d1896\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25153ff elementor-widget elementor-widget-image\" data-id=\"25153ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-monks-at-work--1024x1024.jpg\" class=\"attachment-large size-large wp-image-17516\" alt=\"Koyasan temple stay monks at work\" srcset=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-monks-at-work--1024x1024.jpg 1024w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-monks-at-work--300x300.jpg 300w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-monks-at-work--150x150.jpg 150w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-monks-at-work--768x768.jpg 768w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-monks-at-work--600x600.jpg 600w, https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-temple-stay-monks-at-work-.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2746ce4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2746ce4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db1467c\" data-id=\"db1467c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a16cbe elementor-widget elementor-widget-spacer\" data-id=\"0a16cbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-520a75f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"520a75f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df8d980\" data-id=\"df8d980\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca4ee48 elementor-widget elementor-widget-heading\" data-id=\"ca4ee48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">OBS\u0141UGA KLIENTA NIECO PONI\u017bEJ OCZEKIWA\u0143<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fab5958 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fab5958\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3474cb\" data-id=\"d3474cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9c3d8b elementor-widget elementor-widget-text-editor\" data-id=\"b9c3d8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Kiedy zapyta\u0142am, w jakiej kolejno\u015bci mam je\u015b\u0107 podane na kolacj\u0119 ma\u0142e dania, mnich odpowiedzia\u0142 w po\u015bpiechu: \u201ejak chcesz\u201d. Podczas jedzenia zauwa\u017cy\u0142am notatk\u0119, kt\u00f3r\u0105 ten sam mnich przyni\u00f3s\u0142 wraz z kolacj\u0105, \u017ce mam zacz\u0105\u0107 od klarownej zupy i zje\u015b\u0107 gor\u0105cy hot pot, gdy si\u0119 zagotuje\u2026 Ma\u0142a rzecz, ale b\u0119d\u0105<\/span><span style=\"font-weight: 400;\">c<\/span><span style=\"font-weight: 400;\"> przyzwyczajona do doskona\u0142ej obs\u0142ugi klienta w Japonii, spodziewa\u0142am si\u0119 nieco lepszej obs\u0142ugi w miejscu w tym przedziale cenowym.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Japo\u0144czycy s\u0105 zazwyczaj bardzo dumni ze swoich lokalnych produkt\u00f3w, kuchni, pochodzenia. W niedrogich pensjonatach, w kt\u00f3rych zwykle si\u0119 zatrzymujemy podczas podr\u00f3\u017cy po Japonii, personel zwykle szczeg\u00f3\u0142owo wyja\u015bnia nam wszystko na temat zakwaterowania i pobliskich restauracji. Ale taka jest r\u00f3\u017cnica mi\u0119dzy ma\u0142ym pensjonatem prowadzonym z pasji a du\u017cym hotelem za\u0142o\u017conym dla zysku. Niestety<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> \u015bwi\u0105tynia Ekoin bardziej przypomina ten drugi.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa4e7be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa4e7be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1bc70e\" data-id=\"f1bc70e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1507481 elementor-widget elementor-widget-heading\" data-id=\"1507481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Recenzje_innych_z_pobytu_w_swiatyni_w_Koyasan\"><\/span>Recenzje innych z pobytu w \u015bwi\u0105tyni w Koyasan<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76b79ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76b79ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d881423\" data-id=\"d881423\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8ee5cb elementor-widget elementor-widget-text-editor\" data-id=\"a8ee5cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Czytaj\u0105c recenzje online innych os\u00f3b, <\/span><span style=\"font-weight: 400;\">zauwa\u017cy\u0142am, \u017ce<\/span><span style=\"font-weight: 400;\"> s\u0105 one w wi\u0119kszo\u015bci bardzo zadowolone z pobytu, wi\u0119c to tylko ja jestem pewnie troch\u0119 wybredna. Je\u015bli ju\u017c na co\u015b narzeka<\/span><span style=\"font-weight: 400;\">no<\/span><span style=\"font-weight: 400;\">, to zwykle skupia<\/span><span style=\"font-weight: 400;\">no<\/span><span style=\"font-weight: 400;\"> si\u0119 na dw\u00f3ch rzeczach. Po pierwsze, cienkie \u015bciany \u015bwi\u0105tyni mog\u0105 nieco utrudnia\u0107 sen ze wzgl\u0119du na d\u017awi\u0119ki z innych pomieszcze\u0144. Po drugie, godziny otwarcia publicznej \u0142a\u017ani (16:00-22:00 i 06:00-09:00) s\u0105 niewygodne.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Szczerze m\u00f3wi\u0105c, <\/span><span style=\"font-weight: 400;\">te opinie<\/span><span style=\"font-weight: 400;\"> nie wydaj<\/span><span style=\"font-weight: 400;\">\u0105<\/span><span style=\"font-weight: 400;\"> mi si\u0119 to <\/span><span style=\"font-weight: 400;\">uzasadnione<\/span><span style=\"font-weight: 400;\">. Wszystkie tradycyjne japo\u0144skie stare domy<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> zamienione w pensjonaty<\/span><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> maj\u0105 te same cechy\/zasady. Nie nale\u017cy zatrzymywa\u0107 si\u0119 w tradycyjnym japo\u0144skim domu, nie m\u00f3wi\u0105c ju\u017c o 1200-letniej \u015bwi\u0105tyni, je\u015bli szukacie najwy\u017cszego komfortu. Do \u015bwi\u0105tyni w Koyasan przyje\u017cd\u017casz po unikatowe do\u015bwiadczenie i to w\u0142a\u015bnie tu dostajesz.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cd26eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cd26eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29b0a91\" data-id=\"29b0a91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fc5d43 elementor-widget elementor-widget-heading\" data-id=\"2fc5d43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"Nocleg_w_swiatyni_Ekoin_czy_warto\"><\/span>Nocleg w \u015bwi\u0105tyni Ekoin: czy warto?<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8482f2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8482f2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59ae3b9\" data-id=\"59ae3b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c97f008 elementor-widget elementor-widget-text-editor\" data-id=\"c97f008\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Je\u015bli szukasz do\u015bwiadczenia poza turystycznym szlakiem, to zdecydowanie nie b\u0119dzie to Koyasan, a przynajmniej nie \u015bwi\u0105tynia Ekoin. Ale je\u015bli szukasz unikatowego do\u015bwiadczenia, kt\u00f3re daje wgl\u0105d w japo\u0144ski buddyzm i <\/span><span style=\"font-weight: 400;\">jego<\/span><span style=\"font-weight: 400;\"> tradycje, to z ca\u0142ego serca polecam!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Chocia\u017c pobyt w \u015bwi\u0105tyni nie jest tani &#8211; za noc dla dwojga zap\u0142acili\u015bmy 40 000 JPY &#8211; to naprawd\u0119 i tak warto. Kolacja i \u015bniadanie, kt\u00f3re s\u0105 wliczone w cen\u0119, s\u0105 przygotowywane z wysokiej jako\u015bci sk\u0142adnik\u00f3w i pi\u0119knie podane. Ten rodzaj posi\u0142k\u00f3w, kt\u00f3re bardziej przypominaj\u0105 sztuk\u0119, nigdy nie jest tani w Japonii.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ponadto poranne modlitwy ze \u015bpiewem mnich\u00f3w i rytua\u0142em ognia (w cenie pobytu) to bardzo wyj\u0105tkowe doznania, kt\u00f3rych prawdopodobnie nie do\u015bwiadczysz nigdzie indziej. Poza tym lokalizacja \u015bwi\u0105tyni Eko-in jest bardzo dogodna, wi\u0119c je\u015bli macie ochot\u0119 na wieczorny spacer po s\u0142ynnym cmentarzu, to jest to bardzo proste. Na koniec tylko dodam, <\/span><span style=\"font-weight: 400;\">\u017ce<\/span><span style=\"font-weight: 400;\"> do\u015bwiadczysz tu troch\u0119 typowo tradycyjnej Japonii, wyk\u0105piesz si\u0119 w \u015bwi\u0105tynnej publicznej \u0142a\u017ani, a w yukacie zjesz \u015bniadanie na macie tatami w pokoju.<\/span><\/p>\n<p><span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.ekoin.jp\/en\/\" target=\"_blank\" rel=\"noopener\">Oficjalna strona \u015awi\u0105tyni Ekoin [KLIKNIJ TUTAJ]<\/a><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Je\u017celi podoba\u0142 Wam si\u0119 ten artyku\u0142 do zapraszam do pozostawienia komentarza. Z ch\u0119ci\u0105 odpowiem na Wasze pytania! \ud83d\ude42\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-285be04d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"285be04d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4284323c\" data-id=\"4284323c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31ddf4e4 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"31ddf4e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mountain\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Jak dobrze zaplanowa\u0107 2-dniowe zwiedzanie Koyasan z noclegiem w \u015bwi\u0105tyni. Co zobaczy\u0107 w Mount Koya, jak dojecha\u0107 + recenzja z mojego pobytu w \u015bwi\u0105tyni. Czy naprawd\u0119 warto?<\/p>\n","protected":false},"author":1,"featured_media":17712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"background-image","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.40000000000000002220446049250313080847263336181640625,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[29],"tags":[],"class_list":["post-17783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-japonia","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zwiedzanie Koyasan w 2 dni | Nocleg w \u015awi\u0105tyni w Japonii<\/title>\n<meta name=\"description\" content=\"Zwiedzanie Koyasan w 2 dni z noclegiem w buddyjskiej \u015bwi\u0105tyni + szczera recenzja z pobytu w \u015bwi\u0105tyni. Czego si\u0119 spodziewa\u0107 i czy by\u0142o warto?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zwiedzanie Koyasan w 2 dni | Nocleg w \u015awi\u0105tyni w Japonii\" \/>\n<meta property=\"og:description\" content=\"Zwiedzanie Koyasan w 2 dni z noclegiem w buddyjskiej \u015bwi\u0105tyni + szczera recenzja z pobytu w \u015bwi\u0105tyni. Czego si\u0119 spodziewa\u0107 i czy by\u0142o warto?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/\" \/>\n<meta property=\"og:site_name\" content=\"Betiful World\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/betifulworld\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/betifulworld\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-06T02:59:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-21T05:43:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Beti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/\"},\"author\":{\"name\":\"Beti\",\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/#\\\/schema\\\/person\\\/4972b1094818bc6c9444706178bf9529\"},\"headline\":\"Zwiedzanie Koyasan w 2 dni &#8211; Nocleg w Buddyjskiej \u015awi\u0105tyni w Japonii\",\"datePublished\":\"2023-07-06T02:59:58+00:00\",\"dateModified\":\"2023-10-21T05:43:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/\"},\"wordCount\":4273,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/#\\\/schema\\\/person\\\/4972b1094818bc6c9444706178bf9529\"},\"image\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/betifulworld.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg\",\"articleSection\":[\"Japonia\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/\",\"url\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/\",\"name\":\"Zwiedzanie Koyasan w 2 dni | Nocleg w \u015awi\u0105tyni w Japonii\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/betifulworld.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg\",\"datePublished\":\"2023-07-06T02:59:58+00:00\",\"dateModified\":\"2023-10-21T05:43:12+00:00\",\"description\":\"Zwiedzanie Koyasan w 2 dni z noclegiem w buddyjskiej \u015bwi\u0105tyni + szczera recenzja z pobytu w \u015bwi\u0105tyni. Czego si\u0119 spodziewa\u0107 i czy by\u0142o warto?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/betifulworld.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg\",\"contentUrl\":\"https:\\\/\\\/betifulworld.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Japan Nepal travel blog\",\"item\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zwiedzanie Koyasan w 2 dni &#8211; Nocleg w Buddyjskiej \u015awi\u0105tyni w Japonii\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/\",\"name\":\"Betiful World\",\"description\":\"Outdoor Travel Blog - Nepal &amp; Japan\",\"publisher\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/#\\\/schema\\\/person\\\/4972b1094818bc6c9444706178bf9529\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/betifulworld.com\\\/pl\\\/#\\\/schema\\\/person\\\/4972b1094818bc6c9444706178bf9529\",\"name\":\"Beti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/betifulworld.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/bw-02-2-e1624446357852.png\",\"url\":\"https:\\\/\\\/betifulworld.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/bw-02-2-e1624446357852.png\",\"contentUrl\":\"https:\\\/\\\/betifulworld.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/bw-02-2-e1624446357852.png\",\"width\":300,\"height\":300,\"caption\":\"Beti\"},\"logo\":{\"@id\":\"https:\\\/\\\/betifulworld.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/bw-02-2-e1624446357852.png\"},\"sameAs\":[\"https:\\\/\\\/betifulworld.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/betifulworld\\\/\",\"https:\\\/\\\/www.instagram.com\\\/betiful_world\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zwiedzanie Koyasan w 2 dni | Nocleg w \u015awi\u0105tyni w Japonii","description":"Zwiedzanie Koyasan w 2 dni z noclegiem w buddyjskiej \u015bwi\u0105tyni + szczera recenzja z pobytu w \u015bwi\u0105tyni. Czego si\u0119 spodziewa\u0107 i czy by\u0142o warto?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/","og_locale":"pl_PL","og_type":"article","og_title":"Zwiedzanie Koyasan w 2 dni | Nocleg w \u015awi\u0105tyni w Japonii","og_description":"Zwiedzanie Koyasan w 2 dni z noclegiem w buddyjskiej \u015bwi\u0105tyni + szczera recenzja z pobytu w \u015bwi\u0105tyni. Czego si\u0119 spodziewa\u0107 i czy by\u0142o warto?","og_url":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/","og_site_name":"Betiful World","article_publisher":"https:\/\/www.facebook.com\/betifulworld\/","article_author":"https:\/\/www.facebook.com\/betifulworld\/","article_published_time":"2023-07-06T02:59:58+00:00","article_modified_time":"2023-10-21T05:43:12+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg","type":"image\/jpeg"}],"author":"Beti","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Beti","Szacowany czas czytania":"21 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#article","isPartOf":{"@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/"},"author":{"name":"Beti","@id":"https:\/\/betifulworld.com\/pl\/#\/schema\/person\/4972b1094818bc6c9444706178bf9529"},"headline":"Zwiedzanie Koyasan w 2 dni &#8211; Nocleg w Buddyjskiej \u015awi\u0105tyni w Japonii","datePublished":"2023-07-06T02:59:58+00:00","dateModified":"2023-10-21T05:43:12+00:00","mainEntityOfPage":{"@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/"},"wordCount":4273,"commentCount":12,"publisher":{"@id":"https:\/\/betifulworld.com\/pl\/#\/schema\/person\/4972b1094818bc6c9444706178bf9529"},"image":{"@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#primaryimage"},"thumbnailUrl":"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg","articleSection":["Japonia"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/","url":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/","name":"Zwiedzanie Koyasan w 2 dni | Nocleg w \u015awi\u0105tyni w Japonii","isPartOf":{"@id":"https:\/\/betifulworld.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#primaryimage"},"image":{"@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#primaryimage"},"thumbnailUrl":"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg","datePublished":"2023-07-06T02:59:58+00:00","dateModified":"2023-10-21T05:43:12+00:00","description":"Zwiedzanie Koyasan w 2 dni z noclegiem w buddyjskiej \u015bwi\u0105tyni + szczera recenzja z pobytu w \u015bwi\u0105tyni. Czego si\u0119 spodziewa\u0107 i czy by\u0142o warto?","breadcrumb":{"@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#primaryimage","url":"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg","contentUrl":"https:\/\/betifulworld.com\/wp-content\/uploads\/2023\/06\/Koyasan-2-Day-Itinerary-Honest-Temple-Stay-Review-1.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/betifulworld.com\/pl\/zwiedzanie-koyasan-w-2-dni-i-nocleg-w-swiatyni-w-japonii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Japan Nepal travel blog","item":"https:\/\/betifulworld.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Zwiedzanie Koyasan w 2 dni &#8211; Nocleg w Buddyjskiej \u015awi\u0105tyni w Japonii"}]},{"@type":"WebSite","@id":"https:\/\/betifulworld.com\/pl\/#website","url":"https:\/\/betifulworld.com\/pl\/","name":"Betiful World","description":"Outdoor Travel Blog - Nepal &amp; Japan","publisher":{"@id":"https:\/\/betifulworld.com\/pl\/#\/schema\/person\/4972b1094818bc6c9444706178bf9529"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/betifulworld.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":["Person","Organization"],"@id":"https:\/\/betifulworld.com\/pl\/#\/schema\/person\/4972b1094818bc6c9444706178bf9529","name":"Beti","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/betifulworld.com\/wp-content\/uploads\/2021\/04\/bw-02-2-e1624446357852.png","url":"https:\/\/betifulworld.com\/wp-content\/uploads\/2021\/04\/bw-02-2-e1624446357852.png","contentUrl":"https:\/\/betifulworld.com\/wp-content\/uploads\/2021\/04\/bw-02-2-e1624446357852.png","width":300,"height":300,"caption":"Beti"},"logo":{"@id":"https:\/\/betifulworld.com\/wp-content\/uploads\/2021\/04\/bw-02-2-e1624446357852.png"},"sameAs":["https:\/\/betifulworld.com\/","https:\/\/www.facebook.com\/betifulworld\/","https:\/\/www.instagram.com\/betiful_world\/"]}]}},"_links":{"self":[{"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/posts\/17783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/comments?post=17783"}],"version-history":[{"count":5,"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/posts\/17783\/revisions"}],"predecessor-version":[{"id":18856,"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/posts\/17783\/revisions\/18856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/media\/17712"}],"wp:attachment":[{"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/media?parent=17783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/categories?post=17783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/betifulworld.com\/pl\/wp-json\/wp\/v2\/tags?post=17783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}